{"id":1336685,"date":"2023-03-02T16:53:18","date_gmt":"2023-03-03T00:53:18","guid":{"rendered":"https:\/\/elboton.com\/?p=1336685"},"modified":"2023-03-02T16:53:35","modified_gmt":"2023-03-03T00:53:35","slug":"esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal","status":"publish","type":"post","link":"https:\/\/elboton.com\/aspen\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/","title":{"rendered":"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal"},"content":{"rendered":"<p>Despu\u00e9s de haber sido vistos juntos en Premios Lo Nuestro, los rumores acerca del posible embarazo de Cazzu y Christian Nodal ha circulado en redes sociales.<\/p>\n<p>Y es que en dicha premiaci\u00f3n adem\u00e1s de v\u00e9rseles muy juntitos y derrochando romance, en algunas im\u00e1genes pudimos ver c\u00f3mo Nodal tomaba a Cazzu del vientre lo que para muchos signific\u00f3 que podr\u00edan estar esperando a un beb\u00e9.<\/p>\n<p>La noticia tom\u00f3 m\u00e1s fuerza luego de que una fuente cercana a ambos confirmara que Cazzu estaba embarazada pero que no lo confirmar\u00edan hasta saber que todo estuviera bien. Seg\u00fan el testimonio de su allegada, ambos decidieron que aunque ten\u00edan una agenda apretada por presentaciones y compromisos musicales, se dar\u00edan espacio para estar juntos y conviviendo en familia.<\/p>\n<p>La fuente mencion\u00f3 que hab\u00edan recibido una &#171;noticia inesperada&#187; por lo que los fans no han parado de enviar mensajes y de especular que pronto nacer\u00e1 su primer hijo.<\/p>\n<p>Hasta el momento ninguno de los dos ha salido ha hablar respecto a esto, sin embargo hace unos d\u00edas la cantante argentina fue abordada por la prensa en el aeropuerto de la Ciudad de M\u00e9xico y al ser cuestionada acerca de la noticia, evadi\u00f3 la pregunta y respondi\u00f3 que &#171;eso era algo que pasaba cuando las personas estaban enamoradas&#187;.<\/p>\n<p>En dicha entrevista, Cazzu tambi\u00e9n fue cuestionada acerca de la relaci\u00f3n pasada de Nodal con Belinda, as\u00ed como de su nueva tema que lanz\u00f3 junto a la argentina Tini, misma que interpretaron juntos en la premiaci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1336687\" data-permalink=\"https:\/\/elboton.com\/aspen\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/attachment\/fxtcgbbsljfwviuk363qgxknwq\/\" data-orig-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/FXTCGBBSLJFWVIUK363QGXKNWQ.jpg\" data-orig-size=\"992,661\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/FXTCGBBSLJFWVIUK363QGXKNWQ.jpg?w=992\" class=\"alignnone wp-image-1336687 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/FXTCGBBSLJFWVIUK363QGXKNWQ.jpg?w=992\" alt=\"\" width=\"992\" height=\"661\" srcset=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/FXTCGBBSLJFWVIUK363QGXKNWQ.jpg 992w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/FXTCGBBSLJFWVIUK363QGXKNWQ.jpg?resize=300,200 300w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/FXTCGBBSLJFWVIUK363QGXKNWQ.jpg?resize=768,512 768w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/FXTCGBBSLJFWVIUK363QGXKNWQ.jpg?resize=503,335 503w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/FXTCGBBSLJFWVIUK363QGXKNWQ.jpg?resize=295,197 295w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de haber sido vistos juntos en Premios Lo Nuestro, los rumores acerca del posible embarazo de Cazzu y Christian Nodal ha circulado en redes sociales. Y es que en dicha premiaci\u00f3n adem\u00e1s de v\u00e9rseles muy juntitos y derrochando romance, en algunas im\u00e1genes pudimos ver c\u00f3mo Nodal tomaba a Cazzu del vientre lo que para [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1336688,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[691,1189],"tags":[919,1431,1247,935],"genre":[],"internal":[],"class_list":["post-1336685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-musica","tag-belinda","tag-cazzu","tag-christian-nodal","tag-embarazo","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal - El Bot\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de haber sido vistos juntos en Premios Lo Nuestro, los rumores acerca del posible embarazo de Cazzu y Christian Nodal ha circulado en redes sociales. Y es que en dicha premiaci\u00f3n adem\u00e1s de v\u00e9rseles muy juntitos y derrochando romance, en algunas im\u00e1genes pudimos ver c\u00f3mo Nodal tomaba a Cazzu del vientre lo que para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-03T00:53:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T00:53:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/SEO-Image-1200x675-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal\",\"datePublished\":\"2023-03-03T00:53:18+00:00\",\"dateModified\":\"2023-03-03T00:53:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/\"},\"wordCount\":278,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg\",\"keywords\":[\"Belinda\",\"Cazzu\",\"Christian Nodal\",\"embarazo\"],\"articleSection\":[\"Entretenimiento\",\"M\u00fasica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/\",\"url\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/\",\"name\":\"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg\",\"datePublished\":\"2023-03-03T00:53:18+00:00\",\"dateModified\":\"2023-03-03T00:53:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg\",\"width\":2538,\"height\":1571,\"caption\":\"Fotograf\u00eda: Getty Images.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/elboton.com\/aspen\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal - El Bot\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal - El Bot\u00f3n","og_description":"Despu\u00e9s de haber sido vistos juntos en Premios Lo Nuestro, los rumores acerca del posible embarazo de Cazzu y Christian Nodal ha circulado en redes sociales. Y es que en dicha premiaci\u00f3n adem\u00e1s de v\u00e9rseles muy juntitos y derrochando romance, en algunas im\u00e1genes pudimos ver c\u00f3mo Nodal tomaba a Cazzu del vientre lo que para [&hellip;]","og_url":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2023-03-03T00:53:18+00:00","article_modified_time":"2023-03-03T00:53:35+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/SEO-Image-1200x675-1.png","type":"image\/png"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal","datePublished":"2023-03-03T00:53:18+00:00","dateModified":"2023-03-03T00:53:35+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/"},"wordCount":278,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg","keywords":["Belinda","Cazzu","Christian Nodal","embarazo"],"articleSection":["Entretenimiento","M\u00fasica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/","url":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/","name":"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg","datePublished":"2023-03-03T00:53:18+00:00","dateModified":"2023-03-03T00:53:35+00:00","breadcrumb":{"@id":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg","width":2538,"height":1571,"caption":"Fotograf\u00eda: Getty Images."},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/elboton.com\/aspen\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/elboton.com\/aspen\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfEsperan un beb\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal","url":"http:\/\/elboton.com\/aspen\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/aspen\/entretenimiento\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg"},"articleSection":"M\u00fasica","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["belinda","cazzu","christian nodal","embarazo"],"dateCreated":"2023-03-03T00:53:18Z","datePublished":"2023-03-03T00:53:18Z","dateModified":"2023-03-03T00:53:35Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfEsperan un beb\\u00e9? Lo que se sabe del posible embarazo de Cazzu y Nodal\",\"url\":\"http:\\\/\\\/elboton.com\\\/aspen\\\/entretenimiento\\\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/aspen\\\/entretenimiento\\\/esperan-un-bebe-lo-que-se-sabe-del-posible-embarazo-de-cazzu-y-nodal\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/GettyImages-1469155511-e1677804778967.jpg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/GettyImages-1469155511-e1677804778967.jpg\"},\"articleSection\":\"M\\u00fasica\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"belinda\",\"cazzu\",\"christian nodal\",\"embarazo\"],\"dateCreated\":\"2023-03-03T00:53:18Z\",\"datePublished\":\"2023-03-03T00:53:18Z\",\"dateModified\":\"2023-03-03T00:53:35Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1469155511-e1677804778967.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/posts\/1336685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/comments?post=1336685"}],"version-history":[{"count":2,"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/posts\/1336685\/revisions"}],"predecessor-version":[{"id":1336690,"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/posts\/1336685\/revisions\/1336690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/media\/1336688"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/media?parent=1336685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/categories?post=1336685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/tags?post=1336685"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/genre?post=1336685"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/aspen\/wp-json\/wp\/v2\/internal?post=1336685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}