{"id":1320168,"date":"2021-09-21T11:07:34","date_gmt":"2021-09-21T18:07:34","guid":{"rendered":"https:\/\/elboton.com\/?p=1320168"},"modified":"2021-09-21T11:07:34","modified_gmt":"2021-09-21T18:07:34","slug":"acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana","status":"publish","type":"post","link":"https:\/\/elboton.com\/los-angeles\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/","title":{"rendered":"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a"},"content":{"rendered":"<p>El cantante mexicano Christian Nodal sigue dando de qu\u00e9 hablar, y es que luego de haber hecho p\u00fablico su compromiso con Belinda y ser nominado al <a href=\"https:\/\/elboton.com\/nacional\/entretenimiento\/premios-billboard-estos-son-los-representantes-del-regional-mexicano-que-participan\/\">mejor \u00e1lbum regional del a\u00f1o<\/a> en los Billboard Music Awards 2021, el d\u00eda de hoy, se enfrent\u00f3 con una acusaci\u00f3n en su contra, esta vez por haber adquirido un animal en peligro de extinci\u00f3n.<\/p>\n<p>Se trata de un peque\u00f1o mono ara\u00f1a al que le dio el nombre de Piaf. El cantante comparti\u00f3 una fotograf\u00eda del mono envuelto en una cobija gris con la leyenda &#171;la princesa de la casa&#187; a trav\u00e9s de sus redes sociales, lo que desat\u00f3 una serie de comentarios y se\u00f1alamientos en su contra.<\/p>\n<p>Algunos usuarios de redes sociales, incitaron a la Procuradur\u00eda Federal de Protecci\u00f3n al Ambiente (PROFEPA) de M\u00e9xico a que se pronunciara ante la situaci\u00f3n, ya que la posesi\u00f3n de este animal est\u00e1 estrictamente regulada. La entidad Voluntarios Informados fue la organizaci\u00f3n encargada de denunciar la situaci\u00f3n. Seg\u00fan se\u00f1alan en su p\u00e1gina de Facebook, el cantante &#171;est\u00e1 siendo c\u00f3mplice de un delito federal al adquirir y presumir recientemente que posee de mascota a un mono ara\u00f1a beb\u00e9&#187;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1320172\" data-permalink=\"https:\/\/elboton.com\/los-angeles\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/attachment\/captura-web_21-9-2021_125947_\/\" data-orig-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/Captura-web_21-9-2021_125947_.jpeg\" data-orig-size=\"344,614\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Captura web_21-9-2021_125947_\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/Captura-web_21-9-2021_125947_.jpeg?w=344\" class=\"alignnone wp-image-1320172 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/Captura-web_21-9-2021_125947_.jpeg?w=344\" alt=\"\" width=\"344\" height=\"614\" srcset=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/Captura-web_21-9-2021_125947_.jpeg 344w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/Captura-web_21-9-2021_125947_.jpeg?resize=168,300 168w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/Captura-web_21-9-2021_125947_.jpeg?resize=188,335 188w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/Captura-web_21-9-2021_125947_.jpeg?resize=213,380 213w\" sizes=\"auto, (max-width: 344px) 100vw, 344px\" \/><\/p>\n<p>Hasta el momento, el cantante no ha respondido a los comentarios de su nueva mascota, pero en M\u00e9xico, es bien sabido que el mono ara\u00f1a se encuentra en la lista de animales en peligro de extinci\u00f3n por una reducci\u00f3n dram\u00e1tica en sus n\u00fameros. Adem\u00e1s de que la ley exige a quien tenga una especie en cautiverio, proporcione un ambiente adecuado para que el animal pueda desenvolverse en su estado natural de la mejor forma.<\/p>\n<p>La denuncia est\u00e1 siendo atendida por las autoridades correspondientes, bajo la premisa generada por dicha organizaci\u00f3n de que &#171;Si un personaje que est\u00e1 constantemente en el ojo p\u00fablico no es siquiera cuestionado por la autoridad, \u00bfQu\u00e9 podemos esperar que suceda en los \u00e1mbitos m\u00e1s clandestinos?.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantante mexicano Christian Nodal sigue dando de qu\u00e9 hablar, y es que luego de haber hecho p\u00fablico su compromiso con Belinda y ser nominado al mejor \u00e1lbum regional del a\u00f1o en los Billboard Music Awards 2021, el d\u00eda de hoy, se enfrent\u00f3 con una acusaci\u00f3n en su contra, esta vez por haber adquirido un [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1320173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[691],"tags":[749],"genre":[],"internal":[],"class_list":["post-1320168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-musica","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a - El Bot\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El cantante mexicano Christian Nodal sigue dando de qu\u00e9 hablar, y es que luego de haber hecho p\u00fablico su compromiso con Belinda y ser nominado al mejor \u00e1lbum regional del a\u00f1o en los Billboard Music Awards 2021, el d\u00eda de hoy, se enfrent\u00f3 con una acusaci\u00f3n en su contra, esta vez por haber adquirido un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-21T18:07:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a\",\"datePublished\":\"2021-09-21T18:07:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/\"},\"wordCount\":352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg\",\"keywords\":[\"M\u00fasica\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/\",\"url\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/\",\"name\":\"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg\",\"datePublished\":\"2021-09-21T18:07:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/elboton.com\/los-angeles\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a - El Bot\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/","og_locale":"es_ES","og_type":"article","og_title":"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a - El Bot\u00f3n","og_description":"El cantante mexicano Christian Nodal sigue dando de qu\u00e9 hablar, y es que luego de haber hecho p\u00fablico su compromiso con Belinda y ser nominado al mejor \u00e1lbum regional del a\u00f1o en los Billboard Music Awards 2021, el d\u00eda de hoy, se enfrent\u00f3 con una acusaci\u00f3n en su contra, esta vez por haber adquirido un [&hellip;]","og_url":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2021-09-21T18:07:34+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg","type":"image\/jpeg"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a","datePublished":"2021-09-21T18:07:34+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/"},"wordCount":352,"commentCount":0,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg","keywords":["M\u00fasica"],"articleSection":["Entretenimiento"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/","url":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/","name":"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg","datePublished":"2021-09-21T18:07:34+00:00","breadcrumb":{"@id":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/elboton.com\/los-angeles\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/elboton.com\/los-angeles\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Acusan a Christian Nodal de abuso animal por comprar un mono ara\u00f1a","url":"http:\/\/elboton.com\/los-angeles\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/los-angeles\/entretenimiento\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg"},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["m\u00fasica"],"dateCreated":"2021-09-21T18:07:34Z","datePublished":"2021-09-21T18:07:34Z","dateModified":"2021-09-21T18:07:34Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Acusan a Christian Nodal de abuso animal por comprar un mono ara\\u00f1a\",\"url\":\"http:\\\/\\\/elboton.com\\\/los-angeles\\\/entretenimiento\\\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/los-angeles\\\/entretenimiento\\\/acusan-a-christian-nodal-de-abuso-animal-por-comprar-un-mono-arana\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/09\\\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/09\\\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"m\\u00fasica\"],\"dateCreated\":\"2021-09-21T18:07:34Z\",\"datePublished\":\"2021-09-21T18:07:34Z\",\"dateModified\":\"2021-09-21T18:07:34Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/09\/2JJJWTFRANCBBLMZAL6NPYNUPM.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1320168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1320168"}],"version-history":[{"count":1,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1320168\/revisions"}],"predecessor-version":[{"id":1320174,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1320168\/revisions\/1320174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/media\/1320173"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1320168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1320168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1320168"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/genre?post=1320168"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/internal?post=1320168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}