{"id":1321862,"date":"2021-12-29T16:19:39","date_gmt":"2021-12-30T00:19:39","guid":{"rendered":"https:\/\/elboton.com\/?p=1321862"},"modified":"2021-12-29T16:19:39","modified_gmt":"2021-12-30T00:19:39","slug":"silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa","status":"publish","type":"post","link":"https:\/\/elboton.com\/los-angeles\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/","title":{"rendered":"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa"},"content":{"rendered":"<p>Hace una semana, Silvia Pinal alarm\u00f3 a sus seguidores, luego de que se diera a conocer que hab\u00eda sido diagnosticada con Covid-19. Afortunadamente, la primera actriz no present\u00f3 s\u00edntomas graves y el d\u00eda de hoy ya se recupera en su casa.<\/p>\n<p>Fue su primog\u00e9nita, Sylvia Pasquel, quien dio los detalles de c\u00f3mo se encuentra su madre y los cuidados que debe de tener en su hogar, pues todav\u00eda los estudios indican que tiene la enfermedad.<\/p>\n<p>Coment\u00f3 que los m\u00e9dicos vieron conveniente que la actriz se recuperara en casa, ya que en el hospital pod\u00eda ser m\u00e1s probable que adquiera una bacteria que pusiera en riesgo su vida.<\/p>\n<p>&#171;El doctor la dio de alta hoy, va a ser trasladada a su casa con el mismo protocolo de terapia intensiva de un hospital, con una enfermera de planta, con todo su equipo y traje anti-covid&#187;, declar\u00f3 la tambi\u00e9n actriz.<\/p>\n<p>Pasquel explic\u00f3 c\u00f3mo ser\u00e1n las visitas que puede recibir en casa: &#171;Solo podemos visitarla una vez en la ma\u00f1ana y una vez en la tarde, una sola persona, no te puedes acercar a ella, tiene que ser la sana distancia y tambi\u00e9n te tienes que disfrazar de astronauta&#187;.<\/p>\n<p>Solo habr\u00e1 que esperar a que las pruebas virales de Silvia Pinal arrojen un resultado negativo para que la actriz pueda ser atendida por su propia familia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1321864\" data-permalink=\"https:\/\/elboton.com\/los-angeles\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/attachment\/silvia-pinal\/\" data-orig-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/Silvia-Pinal.jpg\" data-orig-size=\"1140,712\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/Silvia-Pinal.jpg?w=1024\" class=\"alignnone wp-image-1321864 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/Silvia-Pinal.jpg?w=1024\" alt=\"Silvia Pinal\" width=\"1024\" height=\"640\" srcset=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/Silvia-Pinal.jpg 1140w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/Silvia-Pinal.jpg?resize=300,187 300w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/Silvia-Pinal.jpg?resize=768,480 768w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/Silvia-Pinal.jpg?resize=1024,640 1024w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/Silvia-Pinal.jpg?resize=536,335 536w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/Silvia-Pinal.jpg?resize=295,184 295w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace una semana, Silvia Pinal alarm\u00f3 a sus seguidores, luego de que se diera a conocer que hab\u00eda sido diagnosticada con Covid-19. Afortunadamente, la primera actriz no present\u00f3 s\u00edntomas graves y el d\u00eda de hoy ya se recupera en su casa. Fue su primog\u00e9nita, Sylvia Pasquel, quien dio los detalles de c\u00f3mo se encuentra su [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1321863,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[691],"tags":[754],"genre":[],"internal":[],"class_list":["post-1321862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-celebridades","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa - El Bot\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Hace una semana, Silvia Pinal alarm\u00f3 a sus seguidores, luego de que se diera a conocer que hab\u00eda sido diagnosticada con Covid-19. Afortunadamente, la primera actriz no present\u00f3 s\u00edntomas graves y el d\u00eda de hoy ya se recupera en su casa. Fue su primog\u00e9nita, Sylvia Pasquel, quien dio los detalles de c\u00f3mo se encuentra su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-30T00:19:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"1307\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa\",\"datePublished\":\"2021-12-30T00:19:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/\"},\"wordCount\":246,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg\",\"keywords\":[\"Celebridades\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/\",\"url\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/\",\"name\":\"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg\",\"datePublished\":\"2021-12-30T00:19:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg\",\"width\":1960,\"height\":1307},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/elboton.com\/los-angeles\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa - El Bot\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/","og_locale":"es_ES","og_type":"article","og_title":"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa - El Bot\u00f3n","og_description":"Hace una semana, Silvia Pinal alarm\u00f3 a sus seguidores, luego de que se diera a conocer que hab\u00eda sido diagnosticada con Covid-19. Afortunadamente, la primera actriz no present\u00f3 s\u00edntomas graves y el d\u00eda de hoy ya se recupera en su casa. Fue su primog\u00e9nita, Sylvia Pasquel, quien dio los detalles de c\u00f3mo se encuentra su [&hellip;]","og_url":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2021-12-30T00:19:39+00:00","og_image":[{"width":1960,"height":1307,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg","type":"image\/jpeg"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa","datePublished":"2021-12-30T00:19:39+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/"},"wordCount":246,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg","keywords":["Celebridades"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/","url":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/","name":"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg","datePublished":"2021-12-30T00:19:39+00:00","breadcrumb":{"@id":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg","width":1960,"height":1307},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/elboton.com\/los-angeles\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/elboton.com\/los-angeles\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Silvia Pinal dej\u00f3 el hospital y ya est\u00e1 en casa","url":"http:\/\/elboton.com\/los-angeles\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/los-angeles\/entretenimiento\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg"},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["celebridades"],"dateCreated":"2021-12-30T00:19:39Z","datePublished":"2021-12-30T00:19:39Z","dateModified":"2021-12-30T00:19:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Silvia Pinal dej\\u00f3 el hospital y ya est\\u00e1 en casa\",\"url\":\"http:\\\/\\\/elboton.com\\\/los-angeles\\\/entretenimiento\\\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/los-angeles\\\/entretenimiento\\\/silvia-pinal-dejo-el-hospital-y-ya-esta-en-casa\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/12\\\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/12\\\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"celebridades\"],\"dateCreated\":\"2021-12-30T00:19:39Z\",\"datePublished\":\"2021-12-30T00:19:39Z\",\"dateModified\":\"2021-12-30T00:19:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/12\/MYHRWSGGWZFLXEPL5T7YVLLH64.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1321862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1321862"}],"version-history":[{"count":1,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1321862\/revisions"}],"predecessor-version":[{"id":1321865,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1321862\/revisions\/1321865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/media\/1321863"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1321862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1321862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1321862"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/genre?post=1321862"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/internal?post=1321862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}