{"id":1323926,"date":"2022-05-10T17:30:30","date_gmt":"2022-05-11T00:30:30","guid":{"rendered":"https:\/\/elboton.com\/?p=1323926"},"modified":"2022-05-20T13:24:24","modified_gmt":"2022-05-20T20:24:24","slug":"entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda","status":"publish","type":"post","link":"https:\/\/elboton.com\/los-angeles\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/","title":{"rendered":"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"Entrevista con Joel DELE\u014cN: empezando de cero pero entrando con todo\" frameborder=\"0\" width=\"500\" height=\"281\" src=\"https:\/\/geo.dailymotion.com\/player.html?video=x8apeuj&#038;\" allowfullscreen allow=\"autoplay; fullscreen; picture-in-picture; web-share\"><\/iframe><\/p>\n<p>\u00bfRecuerdas a CNCO, la boyband que lo rompi\u00f3 todo con sencillos como &#8216;Quisiera&#8217; o &#8216;Tan F\u00e1cil? Pues hace poco tuve la oportunidad de platicar con Joel DELE\u014cN, el l\u00edder indiscutible de la agrupaci\u00f3n, quien pas\u00f3 de ser un integrante de la hermandad de los cinco, a aventurarse en una carrera en solitario que al fin consiguiera &#171;apaciguar&#187; esas ganas que ten\u00eda de comerse la escena.<\/p>\n<p>Joel es un artista del que hemos escuchado bastante en los \u00faltimos meses. No solo es su forma de bailar y moverse en el escenario, es la manera en que su m\u00fasica rompe las listas de reproducciones y en que sus canciones se meten en los o\u00eddos para hacernos bailar al comp\u00e1s de un loop exquisito.<\/p>\n<p>Un m\u00fasico que opt\u00f3 por componer a su manera, seguir a su coraz\u00f3n y entregarle a sus seguidores una parte de su alma que hasta el momento no conoc\u00edan.<\/p>\n<p>Hace poco, Joel lanz\u00f3 sus primeros dos sencillos. El n\u00famero uno fue &#8216;La Culpa&#8217;, un single en el que explor\u00f3 una versi\u00f3n de s\u00ed mismo que hab\u00eda dejado en el pasado y que lo hab\u00eda conectado en primer lugar con la m\u00fasica: su abuelo. Su lado rom\u00e1ntico y regional afinaron su creatividad y el track que suena a corrido ya cuenta con m\u00e1s de 4 millones de reproducciones en YouTube.<\/p>\n<p>Despu\u00e9s lanz\u00f3 &#8216;Coco&#8217;. Un sencillo que celebra la vida y que refleja el &#171;sabor&#187; con el que DELE\u014cN vive la suya, mediante los ritmos del dembow y el reguet\u00f3n lento. Con esta canci\u00f3n, Joel demuestra la versatilidad de su ingenio y algunos chispazos de lo que ser\u00e1 la carrera de alguien con mucho talento.<\/p>\n<p>\u00a1Checa la conversaci\u00f3n completa y no te olvides de seguirlo de cerca porque pronto estar\u00e1 lanzando m\u00fasica nueva!<\/p>\n<p><iframe loading=\"lazy\" title=\"Joel DELE\u014cN - COCO (Official Video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/p3gkqIVBU-A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>Me gustar\u00eda comenzar con tus primeros pasos en la m\u00fasica, un poco antes de CNCO. \u00bfC\u00f3mo fue que diste con ella y que te fuiste por ese camino?<\/strong><\/p>\n<p>Creo que hay etapas en donde estuve acerc\u00e1ndome mucho m\u00e1s a la m\u00fasica. La primera fue de chiquitito, siempre escuchando m\u00fasica muy vieja como Elvis Presley, The Beatles, Grease (1978) la pel\u00edcula. Despu\u00e9s, como a los siete a\u00f1os, empec\u00e9 a cantar en todos lados y empec\u00e9 a cantar en casa de mis abuelos y por ah\u00ed fue cuando mi abuelito me ense\u00f1\u00f3 una canci\u00f3n y ah\u00ed supe que pod\u00eda cantar.<\/p>\n<p>Despu\u00e9s de un tiempo, cuando cumpl\u00ed 10 a\u00f1os, lo dej\u00e9 de lado porque estaba muy enfocado en el f\u00fatbol y pues nada, cuando entr\u00e9 al High School empec\u00e9 a hacer Vine, que, era una aplicaci\u00f3n de seis segundos en la que empec\u00e9 a hacer covers y entonces ah\u00ed hice una canci\u00f3n y a la gente le gust\u00f3.<\/p>\n<p>Entonces me di cuenta otra vez de que a la gente le estaba gustando lo que hac\u00eda con la m\u00fasica y pues nada, poco a poco, \u00bfSabes? Luego mi mam\u00e1 me mencion\u00f3 de la audici\u00f3n de la banda y despu\u00e9s de ah\u00ed todo empez\u00f3.<\/p>\n<p><b>\u00bfRecuerdas c\u00f3mo se llamaba la canci\u00f3n que te ense\u00f1\u00f3\u00a0tu abuelo?<\/b><\/p>\n<p>Claro, se llama &#8216;100 Ovejas&#8217;.<\/p>\n<p><strong>\u00bfQu\u00e9 fue primero, el baile o la m\u00fasica?\u00a0<\/strong><\/p>\n<p>Yo creo que la parte de m\u00fasica, aunque mi mam\u00e1 de chiquitos a mi familia y a todos mis primos, siempre nos hac\u00edan una coreograf\u00eda para toda la familia, en cualquier ocasi\u00f3n, en Navidad, los cumplea\u00f1os y todo eso. Entonces como que siempre hubo como una mezcla entre el baile y la m\u00fasica desde chiquito.<\/p>\n<p><strong>Cu\u00e9ntame de tu participaci\u00f3n en CNCO \u00bfC\u00f3mo comenz\u00f3 todo?<\/strong><\/p>\n<p>Bueno, pues empez\u00f3 con la audici\u00f3n de la banda. Hab\u00edan un poco m\u00e1s de 10 mil chicos en todos los Estados Unidos, y Puerto Rico y nada, poco a poco la gente empez\u00f3 a votar. Los jueces empezaron a mezclarnos con otros chicos para ver c\u00f3mo conect\u00e1bamos entre nosotros y al final fueron las fans las que votaron y quedamos los cinco.<\/p>\n<p>Despu\u00e9s de eso fue como un cambio de 180 en mi vida, \u00bfSabes? Antes iba a la escuela y todo normal, nunca pens\u00e9 que iba a vivir este sue\u00f1o tan r\u00e1pido, aunque lo ten\u00eda muy pensado y pues a larga estoy muy agradecido con la oportunidad aunque ahora estoy con mi propia m\u00fasica.<\/p>\n<figure id=\"attachment_1323921\" aria-describedby=\"caption-attachment-1323921\" style=\"width: 683px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1323921\" data-permalink=\"https:\/\/elboton.com\/los-angeles\/entretenimiento\/entrevista-con-joel-deleon-empezando-de-cero-pero-entrando-con-todo\/attachment\/img_9119\/\" data-orig-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119.jpg\" data-orig-size=\"1365,2048\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;ILCE-7RM4&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1646854214&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;70&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Fotograf\u00eda: Sony Music Latin.&lt;\/p&gt;\n\" data-large-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119.jpg?w=683\" class=\"wp-image-1323921 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119.jpg?w=683\" alt=\"\" width=\"683\" height=\"1024\" srcset=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119.jpg 1365w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119.jpg?resize=200,300 200w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119.jpg?resize=768,1152 768w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119.jpg?resize=683,1024 683w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119.jpg?resize=1024,1536 1024w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119.jpg?resize=223,335 223w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119.jpg?resize=253,380 253w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption id=\"caption-attachment-1323921\" class=\"wp-caption-text\">Fotograf\u00eda: Sony Music Latin.<\/figcaption><\/figure>\n<p><strong>Hubo mucho ruido con la noticia de que dejabas la banda \u00bfC\u00f3mo pas\u00f3? \u00bfPor qu\u00e9 tomaste la decisi\u00f3n de comenzar tu propia carrera?<\/strong><\/p>\n<p>Durante la pandemia tuve mucho tiempo solo para poder pensar en lo que quer\u00eda empezar a hacer. Muchas ideas que me llegaban\u00a0 a la mente y no quer\u00eda encerrarme, sent\u00eda que ten\u00eda que expresarlas. Entonces nada, se los dije y al principio se quedaron en shock, pero as\u00ed fue.<\/p>\n<p>Las bandas de hoy en d\u00eda al final uno se va, pero siguen siendo mis hermanos, ellos saben que es parte del trabajo y el trabajo es algo completamente diferente. Con la amistad estamos s\u00faper bien, ellos todav\u00eda siguen haciendo m\u00fasica, estamos ah\u00ed apoy\u00e1ndonos al 100 por ciento.<\/p>\n<p><strong>\u00bfFue dif\u00edcil elegir una canci\u00f3n para que se convirtiera en t\u00fa primer sencillo? \u00bfC\u00f3mo viviste ese proceso?<\/strong><\/p>\n<p>Pues f\u00edjate que s\u00ed y te dir\u00eda que s\u00ed, porque siempre estoy en el estudio, siempre estoy creando nueva m\u00fasica. Entonces en cuanto hago una nueva canci\u00f3n digo &#171;quiero que esta canci\u00f3n sea la pr\u00f3xima&#187;, pero ya aprend\u00ed que todas van a salir eventualmente. Hay que ser paciente. Hay que tener una estrategia, porque si cambio un sencillo a otro la estrategia ya no va a funcionar. Entonces pues nada, al principio s\u00ed era un poco dif\u00edcil, pero ya con un plan que tengo ah\u00ed armado la verdad es que todo ha fluido s\u00faper bien.<\/p>\n<p><strong>Plat\u00edcame un poco de \u2018La Culpa\u2019. \u00bfC\u00f3mo fue el proceso de composici\u00f3n y por qu\u00e9 elegiste el corrido como primer tema?<\/strong><\/p>\n<p>Todo pas\u00f3 cuando llegu\u00e9 al estudio y les dije &#171;Hey, quiero hacer una canci\u00f3n del g\u00e9nero que cantaba mi abuelito&#187; o sea de ese estilo. \u00c9l cantaba ranchera, pero ah\u00ed obviamente le a\u00f1ad\u00ed un poco de mi flow, que es un poco m\u00e1s de lo urbano y todo eso. Y pues nada, la verdad que es algo s\u00faper r\u00e1pido, s\u00faper cool. Uno de los productores sac\u00f3 la guitarra con el primer acorde, me sali\u00f3 el coro, la melod\u00eda y la verdad es que me encant\u00f3 el proceso de hacer una canci\u00f3n de ese estilo y eventualmente pues estar\u00e9 haciendo m\u00e1s cosas as\u00ed.<\/p>\n<p><strong>Y un par de meses despu\u00e9s lanzaste \u2018Coco\u2019&#8230; Cu\u00e9ntame un poquito de este tema y de lo que quer\u00edas decir con \u00e9l.<\/strong><\/p>\n<p>Bueno, pues era una canci\u00f3n en donde quer\u00eda hablar del amor. Ahora que habl\u00e9 mucho desamor en &#8216;La Culpa&#8217;, quer\u00eda expresar el otro lado de m\u00ed y de lo que estaba viviendo en ese momento. La verdad que tambi\u00e9n sali\u00f3 s\u00faper cool, s\u00faper r\u00e1pido con DallasK que es el productor y finalmente les ha gustado mucho.<\/p>\n<p>Es una canci\u00f3n s\u00faper bailable, una canci\u00f3n movida que puedes disfrutar en la playa, en la ducha, en el club, en donde sea. As\u00ed que yo estoy s\u00faper emocionado de poder ver que otra vez. est\u00e1n recibiendo mi m\u00fasica con las manos y los brazos abiertos.<\/p>\n<p><strong>Ahora que ya eres un artista solitario, \u00bfC\u00f3mo ha cambiado tu proceso para componer y crear canciones?<\/strong><\/p>\n<p>Pues en CNCO obviamente me gust\u00f3 todo lo que hac\u00edamos, pero siento que lleg\u00f3 un tiempo en donde ya hab\u00eda como un rol, alguien cantaba el rap, alguien cantaba la nota m\u00e1s alta, alguien cantaba las partes m\u00e1s dulces, entonces sent\u00eda que a veces si yo quer\u00eda cantar el rap no se daba porque ya hab\u00eda alguien que desde el principio lo hac\u00eda.<\/p>\n<p>Hoy en d\u00eda cuando hago m\u00fasica me siento mucho m\u00e1s libre, siento que ahora pueden conocer un lado de m\u00ed que nunca han conocido y eso de verdad me emociona mucho, porque \u00faltimamente, este \u00faltimo a\u00f1o, de ser solista me ha ense\u00f1ado muchas cosas, me ha ense\u00f1ado partes de m\u00ed que ni yo conoc\u00eda, as\u00ed que me emociona mucho poder compartirles todo lo que tengo ah\u00ed guardado.<\/p>\n<p><strong>\u00bfC\u00f3mo has sentido a tus fans con tu nueva m\u00fasica?<\/strong><\/p>\n<p>S\u00faper bien, la verdad que me sorprenden cada d\u00eda m\u00e1s, siempre me est\u00e1n apoyando. Siempre me he sentido muy cercano a ellos, siempre est\u00e1n ah\u00ed para apoyarme, para decirme todo, la verdad que me siento muy bien acompa\u00f1ado al lado de todos ellos. Son una gran raz\u00f3n por la cual estoy aqu\u00ed, as\u00ed que yo siempre estar\u00e9 muy agradecido con ellos.<\/p>\n<figure id=\"attachment_1323922\" aria-describedby=\"caption-attachment-1323922\" style=\"width: 683px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1323922\" data-permalink=\"https:\/\/elboton.com\/los-angeles\/entretenimiento\/entrevista-con-joel-deleon-empezando-de-cero-pero-entrando-con-todo\/attachment\/img_0095-257258501\/\" data-orig-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg\" data-orig-size=\"1536,2304\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;ILCE-7M3&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1641255523&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Fotograf\u00eda: Sony Music Latin.&lt;\/p&gt;\n\" data-large-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg?w=683\" class=\"wp-image-1323922 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg?w=683\" alt=\"\" width=\"683\" height=\"1024\" srcset=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg 1536w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg?resize=200,300 200w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg?resize=768,1152 768w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg?resize=683,1024 683w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg?resize=1024,1536 1024w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg?resize=1365,2048 1365w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg?resize=223,335 223w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_0095-257258501.jpg?resize=253,380 253w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption id=\"caption-attachment-1323922\" class=\"wp-caption-text\">Fotograf\u00eda: Sony Music Latin.<\/figcaption><\/figure>\n<p><strong>Una parte de ti tambi\u00e9n es muy fan de la moda, el estilo y de crear una personalidad a trav\u00e9s de la ropa. \u00bfC\u00f3mo surgi\u00f3 esto? <\/strong><\/p>\n<p>Pues desde chiquitito siempre he sido muy &#171;piqui&#187; con mi ropa y me acuerdo que mi mam\u00e1 siempre nos vest\u00eda a los cuatro, porque somos cuatro hombres hermanos y nada, ella siempre nos vest\u00eda s\u00faper lindo y todo pero lleg\u00f3 hasta que cumpl\u00ed nueve y le dije &#171;mami, ya por favor, d\u00e9jame a m\u00ed vestirme&#187; (risas). Y eso, siempre he estado muy metido en lo que es el estilo, la moda y a veces la gente me pregunta &#171;\u00bfQui\u00e9n es tu stylist?&#187; y yo digo que &#171;yo soy mi propio stylist&#187;.<\/p>\n<p>Eventualmente me encantar\u00eda tener una l\u00ednea de ropa ya es una meta.<\/p>\n<p><strong>Plat\u00edcanos un poquito de tu faceta como futbolista, sabemos que eres s\u00faper fan del deporte&#8230;<\/strong><\/p>\n<p>Yo jugaba f\u00fatbol desde los tres a\u00f1os y hasta los 15. Despu\u00e9s de los 15 me fui m\u00e1s al lado de la actuaci\u00f3n en el teatro. No s\u00e9, me llam\u00f3 mucho la atenci\u00f3n y ah\u00ed fue m\u00e1s o menos donde empec\u00e9 a meterme a la m\u00fasica, pero el f\u00fatbol siempre ha sido una pasi\u00f3n muy grande m\u00eda.<\/p>\n<p>En el High School jugaba. Era muy fan del Barcelona y a veces del Real Madrid (risas) depende del a\u00f1o y del equipo.\u00a0 Nunca he sido s\u00faper fiel como para decir &#171;este es mi equipo para siempre&#187;.<\/p>\n<p><strong>Por \u00faltimo, por ac\u00e1 nos gusta saber algunos de los gustos musicales actuales de los artistas. \u00bfPodr\u00edas darnos algunas recomendaciones para los seguidores?<\/strong><\/p>\n<p>Claro, bueno, les puedo recomendar escuchar a la gente con quien me encantar\u00eda colaborar como Jhayco, C. Tangana, Nathy Peluso, Joel DELE\u014cN (risas), mucha gente. Si quieren escuchar algo de throwback, Elvis Presley, The Beatles, la verdad es que me llaman mucho la atenci\u00f3n las bandas de antes.<\/p>\n<p><iframe loading=\"lazy\" title=\"Joel DELE\u014cN \u2013 La Culpa (Official Video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/nauFl7tpEF4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfRecuerdas a CNCO, la boyband que lo rompi\u00f3 todo con sencillos como &#8216;Quisiera&#8217; o &#8216;Tan F\u00e1cil? Pues hace poco tuve la oportunidad de platicar con Joel DELE\u014cN, el l\u00edder indiscutible de la agrupaci\u00f3n, quien pas\u00f3 de ser un integrante de la hermandad de los cinco, a aventurarse en una carrera en solitario que al fin [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1323927,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[1262],"tags":[1345,1346,1344],"genre":[],"internal":[],"class_list":["post-1323926","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-videos","tag-cnco","tag-joel-deleon","tag-joel-pimentel","post_format-post-format-video","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda - El Bot\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"\u00bfRecuerdas a CNCO, la boyband que lo rompi\u00f3 todo con sencillos como &#8216;Quisiera&#8217; o &#8216;Tan F\u00e1cil? Pues hace poco tuve la oportunidad de platicar con Joel DELE\u014cN, el l\u00edder indiscutible de la agrupaci\u00f3n, quien pas\u00f3 de ser un integrante de la hermandad de los cinco, a aventurarse en una carrera en solitario que al fin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-11T00:30:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-20T20:24:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1360\" \/>\n\t<meta property=\"og:image:height\" content=\"847\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda\",\"datePublished\":\"2022-05-11T00:30:30+00:00\",\"dateModified\":\"2022-05-20T20:24:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/\"},\"wordCount\":1923,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg\",\"keywords\":[\"CNCO\",\"Joel DELE\u00d3N\",\"Joel Pimentel\"],\"articleSection\":[\"Videos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/\",\"url\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/\",\"name\":\"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg\",\"datePublished\":\"2022-05-11T00:30:30+00:00\",\"dateModified\":\"2022-05-20T20:24:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg\",\"width\":1360,\"height\":847,\"caption\":\"Fotograf\u00eda: Sony Music Latin.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/elboton.com\/los-angeles\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda - El Bot\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda - El Bot\u00f3n","og_description":"\u00bfRecuerdas a CNCO, la boyband que lo rompi\u00f3 todo con sencillos como &#8216;Quisiera&#8217; o &#8216;Tan F\u00e1cil? Pues hace poco tuve la oportunidad de platicar con Joel DELE\u014cN, el l\u00edder indiscutible de la agrupaci\u00f3n, quien pas\u00f3 de ser un integrante de la hermandad de los cinco, a aventurarse en una carrera en solitario que al fin [&hellip;]","og_url":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2022-05-11T00:30:30+00:00","article_modified_time":"2022-05-20T20:24:24+00:00","og_image":[{"width":1360,"height":847,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg","type":"image\/jpeg"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda","datePublished":"2022-05-11T00:30:30+00:00","dateModified":"2022-05-20T20:24:24+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/"},"wordCount":1923,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg","keywords":["CNCO","Joel DELE\u00d3N","Joel Pimentel"],"articleSection":["Videos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/","url":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/","name":"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg","datePublished":"2022-05-11T00:30:30+00:00","dateModified":"2022-05-20T20:24:24+00:00","breadcrumb":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg","width":1360,"height":847,"caption":"Fotograf\u00eda: Sony Music Latin."},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/elboton.com\/los-angeles\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/elboton.com\/los-angeles\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Entrevista con Joel DELE\u014cN: cuando el talento no cabe en una banda","url":"http:\/\/elboton.com\/los-angeles\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/los-angeles\/videos\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg"},"articleSection":"Videos","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["cnco","joel dele\u00f3n","joel pimentel"],"dateCreated":"2022-05-11T00:30:30Z","datePublished":"2022-05-11T00:30:30Z","dateModified":"2022-05-20T20:24:24Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Entrevista con Joel DELE\\u014cN: cuando el talento no cabe en una banda\",\"url\":\"http:\\\/\\\/elboton.com\\\/los-angeles\\\/videos\\\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/los-angeles\\\/videos\\\/entrevista-con-joel-deleon-cuando-el-talento-no-cabe-en-una-banda\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/05\\\/IMG_9119-1-e1652228466173.jpg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/05\\\/IMG_9119-1-e1652228466173.jpg\"},\"articleSection\":\"Videos\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"cnco\",\"joel dele\\u00f3n\",\"joel pimentel\"],\"dateCreated\":\"2022-05-11T00:30:30Z\",\"datePublished\":\"2022-05-11T00:30:30Z\",\"dateModified\":\"2022-05-20T20:24:24Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/05\/IMG_9119-1-e1652228466173.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1323926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1323926"}],"version-history":[{"count":9,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1323926\/revisions"}],"predecessor-version":[{"id":1324127,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1323926\/revisions\/1324127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/media\/1323927"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1323926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1323926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1323926"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/genre?post=1323926"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/internal?post=1323926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}