{"id":1325587,"date":"2022-08-01T11:01:56","date_gmt":"2022-08-01T18:01:56","guid":{"rendered":"https:\/\/elboton.com\/?p=1325587"},"modified":"2022-08-01T11:01:57","modified_gmt":"2022-08-01T18:01:57","slug":"graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel","status":"publish","type":"post","link":"https:\/\/elboton.com\/los-angeles\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/","title":{"rendered":"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel"},"content":{"rendered":"<p>Este fin de semana se vivi\u00f3 el concierto de los reguetoneros Wisin y Yandel en Guatemala, donde extra\u00f1amente se capt\u00f3 a la pareja del momento Cazzu y Christian Nodal mientras disfrutaban del espect\u00e1culo y se besaban en repetidas ocasiones.<\/p>\n<p>Fue un conductor de la televisi\u00f3n de Guatemala, quien comparti\u00f3 los clips en sus historias de Instagram en los cuales se les ve bailando y brincando con las canciones de los puertorrique\u00f1os, adem\u00e1s de la historia que comparti\u00f3 la argentina en su cuenta de Instagram, en donde se puede ver que uno de los integrantes del d\u00fao la se\u00f1ala.<\/p>\n<p>Cabe se\u00f1alar que en las historias del periodista, vemos que Cazzu y Nodal se encuentran hasta el frente del escenario, a unos cuantos metros de las estrellas de la noche.<\/p>\n<p>Por alguna raz\u00f3n, tanto Cazzu como Nodal disfrutan del tiempo en Guatemala, ya que este ha sido el pa\u00eds en el que se les ha estado encontrando en repetidas ocasiones, as\u00ed como la primera vez en la que caminaban por las calles tomados de la mano.<\/p>\n<p>Por \u00faltimo, recordar que ambos artistas han estado compartiendo distintas fotograf\u00edas juntos a trav\u00e9s de sus cuentas de Instagram, en el que se les ve juntos y pas\u00e1ndola bien. Tal es el caso de la \u00faltima fotograf\u00eda que Nodal poste\u00f3 en el que se observa a la argentina disfrutando de un chapuz\u00f3n en la alberca junto a sus amigas, mientras que \u00e9l est\u00e1 recostado viendo &#171;Malcolm El De En Medio&#187; en su tablet.<\/p>\n<p>Aunque ambos se han mantenido discretos ante su noviazgo, las evidencias apuntan a que esto es m\u00e1s que un hecho y dicen por ah\u00ed, que Cazzu podr\u00eda estar embarazada.<\/p>\n<p><a href=\"https:\/\/www.tiktok.com\/@nodal_fans\/video\/7126401635219213573?is_copy_url=1&#038;is_from_webapp=v1&#038;q=cazzu%20nodal&#038;t=1659376507281\" rel=\"nofollow\">https:\/\/www.tiktok.com\/@nodal_fans\/video\/7126401635219213573?is_copy_url=1&#038;is_from_webapp=v1&#038;q=cazzu%20nodal&#038;t=1659376507281<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana se vivi\u00f3 el concierto de los reguetoneros Wisin y Yandel en Guatemala, donde extra\u00f1amente se capt\u00f3 a la pareja del momento Cazzu y Christian Nodal mientras disfrutaban del espect\u00e1culo y se besaban en repetidas ocasiones. Fue un conductor de la televisi\u00f3n de Guatemala, quien comparti\u00f3 los clips en sus historias de [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1325588,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[691,1189],"tags":[1431,1247,1561],"genre":[],"internal":[],"class_list":["post-1325587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-musica","tag-cazzu","tag-christian-nodal","tag-wisin-y-yandel","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel - El Bot\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Este fin de semana se vivi\u00f3 el concierto de los reguetoneros Wisin y Yandel en Guatemala, donde extra\u00f1amente se capt\u00f3 a la pareja del momento Cazzu y Christian Nodal mientras disfrutaban del espect\u00e1culo y se besaban en repetidas ocasiones. Fue un conductor de la televisi\u00f3n de Guatemala, quien comparti\u00f3 los clips en sus historias de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-01T18:01:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-01T18:01:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel\",\"datePublished\":\"2022-08-01T18:01:56+00:00\",\"dateModified\":\"2022-08-01T18:01:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/\"},\"wordCount\":328,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png\",\"keywords\":[\"Cazzu\",\"Christian Nodal\",\"Wisin Y Yandel\"],\"articleSection\":[\"Entretenimiento\",\"M\u00fasica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/\",\"url\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/\",\"name\":\"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png\",\"datePublished\":\"2022-08-01T18:01:56+00:00\",\"dateModified\":\"2022-08-01T18:01:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png\",\"width\":1280,\"height\":640,\"caption\":\"Fotograf\u00eda: Getty Images.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/elboton.com\/los-angeles\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel - El Bot\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/","og_locale":"es_ES","og_type":"article","og_title":"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel - El Bot\u00f3n","og_description":"Este fin de semana se vivi\u00f3 el concierto de los reguetoneros Wisin y Yandel en Guatemala, donde extra\u00f1amente se capt\u00f3 a la pareja del momento Cazzu y Christian Nodal mientras disfrutaban del espect\u00e1culo y se besaban en repetidas ocasiones. Fue un conductor de la televisi\u00f3n de Guatemala, quien comparti\u00f3 los clips en sus historias de [&hellip;]","og_url":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2022-08-01T18:01:56+00:00","article_modified_time":"2022-08-01T18:01:57+00:00","og_image":[{"width":1280,"height":640,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png","type":"image\/png"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel","datePublished":"2022-08-01T18:01:56+00:00","dateModified":"2022-08-01T18:01:57+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/"},"wordCount":328,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png","keywords":["Cazzu","Christian Nodal","Wisin Y Yandel"],"articleSection":["Entretenimiento","M\u00fasica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/","url":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/","name":"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png","datePublished":"2022-08-01T18:01:56+00:00","dateModified":"2022-08-01T18:01:57+00:00","breadcrumb":{"@id":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png","width":1280,"height":640,"caption":"Fotograf\u00eda: Getty Images."},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/elboton.com\/los-angeles\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/elboton.com\/los-angeles\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Graban a Cazzu y Nodal bes\u00e1ndose en el concierto de Wisin y Yandel","url":"http:\/\/elboton.com\/los-angeles\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/los-angeles\/entretenimiento\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png"},"articleSection":"M\u00fasica","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["cazzu","christian nodal","wisin y yandel"],"dateCreated":"2022-08-01T18:01:56Z","datePublished":"2022-08-01T18:01:56Z","dateModified":"2022-08-01T18:01:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Graban a Cazzu y Nodal bes\\u00e1ndose en el concierto de Wisin y Yandel\",\"url\":\"http:\\\/\\\/elboton.com\\\/los-angeles\\\/entretenimiento\\\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/los-angeles\\\/entretenimiento\\\/graban-a-cazzu-y-nodal-besandose-en-el-concierto-de-wisin-y-yandel\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/08\\\/2-1.png?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/08\\\/2-1.png\"},\"articleSection\":\"M\\u00fasica\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"cazzu\",\"christian nodal\",\"wisin y yandel\"],\"dateCreated\":\"2022-08-01T18:01:56Z\",\"datePublished\":\"2022-08-01T18:01:56Z\",\"dateModified\":\"2022-08-01T18:01:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/08\/2-1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1325587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1325587"}],"version-history":[{"count":1,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1325587\/revisions"}],"predecessor-version":[{"id":1325589,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1325587\/revisions\/1325589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/media\/1325588"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1325587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1325587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1325587"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/genre?post=1325587"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/internal?post=1325587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}