{"id":1352316,"date":"2026-04-19T09:55:56","date_gmt":"2026-04-19T16:55:56","guid":{"rendered":"https:\/\/elboton.com\/?p=1352316"},"modified":"2026-04-19T09:55:56","modified_gmt":"2026-04-19T16:55:56","slug":"politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente","status":"publish","type":"post","link":"https:\/\/elboton.com\/los-angeles\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/","title":{"rendered":"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente"},"content":{"rendered":"<p>En este episodio de\u00a0<strong>Politics con Acento<\/strong>\u00a0te mostramos c\u00f3mo la pol\u00edtica no se queda en Washington: se mete en tu bolsillo, en tu familia y en tu futuro. Desde la batalla rumbo a las elecciones de medio t\u00e9rmino y la guerra interna entre republicanos y dem\u00f3cratas, hasta la crisis migratoria, las detenciones, los impuestos y la seguridad rumbo al Mundial 2026.<\/p>\n<p>Este programa re\u00fane an\u00e1lisis, entrevistas clave, reportaje en la frontera y servicio comunitario con informaci\u00f3n que s\u00ed te afecta. Y cerramos con un momento fuerte y humano junto a\u00a0<strong>Laura Zapata<\/strong>, hablando sin filtros sobre el dolor migrante.<\/p>\n<p><iframe loading=\"lazy\" title=\"POLITICS CON ACENTO EP.4 |19 Abril de 2026 | GUERRA POL\u00cdTICA | DOLOR MIGRANTE | BECERRA RESPONDE\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/hNGp3E1fr1I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este episodio de\u00a0Politics con Acento\u00a0te mostramos c\u00f3mo la pol\u00edtica no se queda en Washington: se mete en tu bolsillo, en tu familia y en tu futuro. Desde la batalla rumbo a las elecciones de medio t\u00e9rmino y la guerra interna entre republicanos y dem\u00f3cratas, hasta la crisis migratoria, las detenciones, los impuestos y la [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1352317,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[691],"tags":[801,2818,2834,2912,784,2832,2816,2910,2830,2911,2909,96],"genre":[],"internal":[],"class_list":["post-1352316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-entrevista","tag-new-episode","tag-nuevo-episodio","tag-pca","tag-podcast","tag-politics","tag-politics-con-acento","tag-sheriff-chad-bianco","tag-stephanie-ochoa","tag-steve-hilton","tag-xavier-becerra","tag-youtube","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente - El Bot\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"En este episodio de\u00a0Politics con Acento\u00a0te mostramos c\u00f3mo la pol\u00edtica no se queda en Washington: se mete en tu bolsillo, en tu familia y en tu futuro. Desde la batalla rumbo a las elecciones de medio t\u00e9rmino y la guerra interna entre republicanos y dem\u00f3cratas, hasta la crisis migratoria, las detenciones, los impuestos y la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-19T16:55:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente\",\"datePublished\":\"2026-04-19T16:55:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/\"},\"wordCount\":128,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg\",\"keywords\":[\"Entrevista\",\"New Episode\",\"Nuevo Episodio\",\"PCA\",\"podcast\",\"Politics\",\"Politics con Acento\",\"Sheriff Chad Bianco\",\"Stephanie Ochoa\",\"Steve Hilton\",\"Xavier Becerra\",\"youtube\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/\",\"url\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/\",\"name\":\"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg\",\"datePublished\":\"2026-04-19T16:55:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/elboton.com\/los-angeles\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente - El Bot\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/","og_locale":"es_ES","og_type":"article","og_title":"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente - El Bot\u00f3n","og_description":"En este episodio de\u00a0Politics con Acento\u00a0te mostramos c\u00f3mo la pol\u00edtica no se queda en Washington: se mete en tu bolsillo, en tu familia y en tu futuro. Desde la batalla rumbo a las elecciones de medio t\u00e9rmino y la guerra interna entre republicanos y dem\u00f3cratas, hasta la crisis migratoria, las detenciones, los impuestos y la [&hellip;]","og_url":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2026-04-19T16:55:56+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg","type":"image\/jpeg"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente","datePublished":"2026-04-19T16:55:56+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/"},"wordCount":128,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg","keywords":["Entrevista","New Episode","Nuevo Episodio","PCA","podcast","Politics","Politics con Acento","Sheriff Chad Bianco","Stephanie Ochoa","Steve Hilton","Xavier Becerra","youtube"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/","url":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/","name":"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg","datePublished":"2026-04-19T16:55:56+00:00","breadcrumb":{"@id":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg","width":2560,"height":1440,"caption":"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente"},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/elboton.com\/los-angeles\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"http:\/\/elboton.com\/nacional\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente","url":"http:\/\/elboton.com\/los-angeles\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/los-angeles\/entretenimiento\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg"},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["entrevista","new episode","nuevo episodio","pca","podcast","politics","politics con acento","sheriff chad bianco","stephanie ochoa","steve hilton","xavier becerra","youtube"],"dateCreated":"2026-04-19T16:55:56Z","datePublished":"2026-04-19T16:55:56Z","dateModified":"2026-04-19T16:55:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Politics con Acento: Elecciones, redadas y crisis, el golpe a nuestra gente\",\"url\":\"http:\\\/\\\/elboton.com\\\/los-angeles\\\/entretenimiento\\\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/los-angeles\\\/entretenimiento\\\/politics-con-acento-elecciones-redadas-y-crisis-el-golpe-a-nuestra-gente\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/04\\\/PCA_Ep_4.jpg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/04\\\/PCA_Ep_4.jpg\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"entrevista\",\"new episode\",\"nuevo episodio\",\"pca\",\"podcast\",\"politics\",\"politics con acento\",\"sheriff chad bianco\",\"stephanie ochoa\",\"steve hilton\",\"xavier becerra\",\"youtube\"],\"dateCreated\":\"2026-04-19T16:55:56Z\",\"datePublished\":\"2026-04-19T16:55:56Z\",\"dateModified\":\"2026-04-19T16:55:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2026\/04\/PCA_Ep_4.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1352316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1352316"}],"version-history":[{"count":1,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1352316\/revisions"}],"predecessor-version":[{"id":1352318,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1352316\/revisions\/1352318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/media\/1352317"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1352316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1352316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1352316"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/genre?post=1352316"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/los-angeles\/wp-json\/wp\/v2\/internal?post=1352316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}