{"id":1319779,"date":"2021-08-25T14:39:13","date_gmt":"2021-08-25T21:39:13","guid":{"rendered":"https:\/\/elboton.com\/?p=1319779"},"modified":"2021-08-25T14:40:09","modified_gmt":"2021-08-25T21:40:09","slug":"el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil","status":"publish","type":"post","link":"https:\/\/elboton.com\/nacional\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/","title":{"rendered":"El &#8216;beb\u00e9 de Nirvana&#8217; demanda al grupo por &#171;pornograf\u00eda infantil&#187;"},"content":{"rendered":"<p>El Bot\u00f3n.- <strong>Spencer Elden<\/strong>, quien apareci\u00f3 <strong>desnudo en la portada del \u00e1lbum \u201cNevermind\u201d de Nirvana cuando era beb\u00e9,<\/strong> describi\u00f3 dicha imagen ic\u00f3nica como <strong>pornograf\u00eda infantil<\/strong> y est\u00e1 <strong>demandando a la banda por presunta explotaci\u00f3n sexual infantil<\/strong>.<\/p>\n<p><strong>La portada del \u00e1lbum de rock de 1991 muestra a Elden beb\u00e9, desnudo y nadando<\/strong> bajo el agua, con los ojos fijos en un billete de un d\u00f3lar.<\/p>\n<p>En la denuncia presentada este martes en un tribunal federal de California y obtenida por CNN, los abogados de Elden dijeron que la imagen era pornogr\u00e1fica y <strong>que el afectado hab\u00eda sufrido \u201cda\u00f1os de por vida\u201d<\/strong> como resultado de su participaci\u00f3n en esta.<\/p>\n<p><a href=\"https:\/\/noticiasya.com\/2021\/08\/18\/demanda-de-johnny-depp-contra-su-exesposa-por-difamacion-ira-a-juicio\/\" target=\"_blank\" rel=\"noopener\">LEE: Demanda de Johnny Depp contra su exesposa por difamaci\u00f3n ir\u00e1 a juicio<\/a><\/p>\n<p><strong>Elden, ahora de 30 a\u00f1os, ha incluido como acusados a los miembros sobrevivientes<\/strong> de la banda, al <strong>fot\u00f3grafo Kirk Weddle<\/strong>, a <strong>la albacea de la herencia del vocalista Kurt Cobain<\/strong> (su viuda, la cantante <strong>Courtney Love<\/strong>) y los sellos discogr\u00e1ficos <strong>Warner Records<\/strong> y <strong>Universal Music Group<\/strong>.<\/p>\n<p><strong>El demandante busca obtener 150 mil d\u00f3lares en da\u00f1os y perjuicios por parte de cada uno de los acusados, m\u00e1s los costos legales<\/strong>, y alega que los acusados \u201c<strong>produjeron, poseyeron y publicitaron pornograf\u00eda infantil comercial a sabiendas<\/strong>\u201d.<\/p>\n<p><a href=\"https:\/\/noticiasya.com\/2021\/08\/11\/escalofriantes-detalles-del-asesinato-de-dos-bebes-en-rosarito-a-manos-de-su-papa\/\" target=\"_blank\" rel=\"noopener\">LEE: Escalofriantes detalles del asesinato de dos beb\u00e9s en Rosarito a manos de su pap\u00e1<\/a><\/p>\n<p>La demanda alega que <strong>Elden \u201cha sufrido y seguir\u00e1 sufriendo da\u00f1os personales por la distribuci\u00f3n y posesi\u00f3n de pornograf\u00eda infantil<\/strong>\u201d, incluida la angustia emocional y la p\u00e9rdida de ingresos.<\/p>\n<p>Tambi\u00e9n acusa que <strong>Elden fue sexualizado <\/strong>porque el billete de un d\u00f3lar usado en la imagen hac\u00eda que el beb\u00e9 pareciera \u201cuna trabajadora sexual\u201d.<\/p>\n<p><a href=\"https:\/\/noticiasya.com\/2021\/08\/19\/onlyfans-vetara-la-pornografia-a-partir-de-octubre-por-un-interes-mayor\/\" target=\"_blank\" rel=\"noopener\">LEE: OnlyFans vetar\u00e1 la pornograf\u00eda a partir de octubre por un inter\u00e9s mayor<\/a><\/p>\n<p><strong>Elden ha recreado la imagen<\/strong> en diversas ocasiones durante su edad adulta, pero <strong>tambi\u00e9n ha sugerido en entrevistas que se sent\u00eda inc\u00f3modo con la popularidad<\/strong> de la portada del \u00e1lbum.<\/p>\n<p>Por ejemplo, en 2007 le dijo a The Sunday Times que le parec\u00eda <strong>\u201cun poco espeluznante que muchas personas me hayan visto desnudo&#8230; Me siento como la estrella porno m\u00e1s grande del mundo\u201d.<\/strong><\/p>\n<p><em>*Con informaci\u00f3n de CNN<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>VIDEO RELACIONADO:<\/p>\n<p>[bc_video video_id=&#187;6116935983001&#8243; account_id=&#187;5443452546001&#8243; player_id=&#187;H9lHBR6NS&#187; embed=&#187;in-page&#187; padding_top=&#187;56%&#187; autoplay=&#187;&#187; min_width=&#187;0px&#187; playsinline=&#187;&#187; picture_in_picture=&#187;&#187; max_width=&#187;640px&#187; mute=&#187;&#187; width=&#187;100%&#187; height=&#187;100%&#187; ]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>30 a\u00f1os despu\u00e9s de aparecer desnudo en la portada del \u00e1lbum &#171;Nevermind&#187;, Spencer Elden arremete contra la legendaria agrupaci\u00f3n<\/p>\n","protected":false},"author":89200938,"featured_media":1319781,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[691],"tags":[749],"genre":[],"internal":[],"class_list":["post-1319779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-musica","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El &#039;beb\u00e9 de Nirvana&#039; demanda al grupo por &quot;pornograf\u00eda infantil&quot; - El Bot\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El &#039;beb\u00e9 de Nirvana&#039; demanda al grupo por &quot;pornograf\u00eda infantil&quot; - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"30 a\u00f1os despu\u00e9s de aparecer desnudo en la portada del \u00e1lbum &quot;Nevermind&quot;, Spencer Elden arremete contra la legendaria agrupaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-25T21:39:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-25T21:40:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernando Quintero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Quintero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/\"},\"author\":{\"name\":\"Fernando Quintero\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/744a29dcf26f4c37a312b138a0724865\"},\"headline\":\"El &#8216;beb\u00e9 de Nirvana&#8217; demanda al grupo por &#171;pornograf\u00eda infantil&#187;\",\"datePublished\":\"2021-08-25T21:39:13+00:00\",\"dateModified\":\"2021-08-25T21:40:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/\"},\"wordCount\":424,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg\",\"keywords\":[\"M\u00fasica\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/\",\"url\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/\",\"name\":\"El 'beb\u00e9 de Nirvana' demanda al grupo por \\\"pornograf\u00eda infantil\\\" - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg\",\"datePublished\":\"2021-08-25T21:39:13+00:00\",\"dateModified\":\"2021-08-25T21:40:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El &#8216;beb\u00e9 de Nirvana&#8217; demanda al grupo por &#171;pornograf\u00eda infantil&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/744a29dcf26f4c37a312b138a0724865\",\"name\":\"Fernando Quintero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4ed65bf070b3b837afd3d5106e866c7217c8e03bd25dd23bd95d7aa50568284b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4ed65bf070b3b837afd3d5106e866c7217c8e03bd25dd23bd95d7aa50568284b?s=96&d=mm&r=g\",\"caption\":\"Fernando Quintero\"},\"url\":\"https:\/\/elboton.com\/nacional\/author\/ferquinteroc\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El 'beb\u00e9 de Nirvana' demanda al grupo por \"pornograf\u00eda infantil\" - El Bot\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/","og_locale":"es_ES","og_type":"article","og_title":"El 'beb\u00e9 de Nirvana' demanda al grupo por \"pornograf\u00eda infantil\" - El Bot\u00f3n","og_description":"30 a\u00f1os despu\u00e9s de aparecer desnudo en la portada del \u00e1lbum \"Nevermind\", Spencer Elden arremete contra la legendaria agrupaci\u00f3n","og_url":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2021-08-25T21:39:13+00:00","article_modified_time":"2021-08-25T21:40:09+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg","type":"image\/jpeg"}],"author":"Fernando Quintero","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Fernando Quintero","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/"},"author":{"name":"Fernando Quintero","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/744a29dcf26f4c37a312b138a0724865"},"headline":"El &#8216;beb\u00e9 de Nirvana&#8217; demanda al grupo por &#171;pornograf\u00eda infantil&#187;","datePublished":"2021-08-25T21:39:13+00:00","dateModified":"2021-08-25T21:40:09+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/"},"wordCount":424,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg","keywords":["M\u00fasica"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/","url":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/","name":"El 'beb\u00e9 de Nirvana' demanda al grupo por \"pornograf\u00eda infantil\" - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg","datePublished":"2021-08-25T21:39:13+00:00","dateModified":"2021-08-25T21:40:09+00:00","breadcrumb":{"@id":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"El &#8216;beb\u00e9 de Nirvana&#8217; demanda al grupo por &#171;pornograf\u00eda infantil&#187;"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/744a29dcf26f4c37a312b138a0724865","name":"Fernando Quintero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4ed65bf070b3b837afd3d5106e866c7217c8e03bd25dd23bd95d7aa50568284b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ed65bf070b3b837afd3d5106e866c7217c8e03bd25dd23bd95d7aa50568284b?s=96&d=mm&r=g","caption":"Fernando Quintero"},"url":"https:\/\/elboton.com\/nacional\/author\/ferquinteroc"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/elboton.com\/nacional\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El &#8216;beb\u00e9 de Nirvana&#8217; demanda al grupo por &#171;pornograf\u00eda infantil&#187;","url":"http:\/\/elboton.com\/nacional\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/nacional\/entretenimiento\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg"},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Fernando Quintero"}],"creator":["Fernando Quintero"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["m\u00fasica"],"dateCreated":"2021-08-25T21:39:13Z","datePublished":"2021-08-25T21:39:13Z","dateModified":"2021-08-25T21:40:09Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El &#8216;beb\\u00e9 de Nirvana&#8217; demanda al grupo por &#171;pornograf\\u00eda infantil&#187;\",\"url\":\"http:\\\/\\\/elboton.com\\\/nacional\\\/entretenimiento\\\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/nacional\\\/entretenimiento\\\/el-bebe-de-nirvana-demanda-al-grupo-por-pornografia-infantil\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/08\\\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/08\\\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Fernando Quintero\"}],\"creator\":[\"Fernando Quintero\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"m\\u00fasica\"],\"dateCreated\":\"2021-08-25T21:39:13Z\",\"datePublished\":\"2021-08-25T21:39:13Z\",\"dateModified\":\"2021-08-25T21:40:09Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2021\/08\/el-beb-de-nirvana-demanda-al-grupo-por-pornografa-infantil.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/posts\/1319779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/users\/89200938"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/comments?post=1319779"}],"version-history":[{"count":1,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/posts\/1319779\/revisions"}],"predecessor-version":[{"id":1319780,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/posts\/1319779\/revisions\/1319780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/media\/1319781"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/media?parent=1319779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/categories?post=1319779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/tags?post=1319779"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/genre?post=1319779"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/internal?post=1319779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}