{"id":1323447,"date":"2022-03-30T14:18:55","date_gmt":"2022-03-30T21:18:55","guid":{"rendered":"https:\/\/elboton.com\/?p=1323447"},"modified":"2022-04-12T15:24:02","modified_gmt":"2022-04-12T22:24:02","slug":"entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion","status":"publish","type":"post","link":"https:\/\/elboton.com\/nacional\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/","title":{"rendered":"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n"},"content":{"rendered":"<div style=\"position:relative;padding-bottom:56.25%;height:0;overflow:hidden;\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><meta itemprop=\"name\" content=\"Entrevista con LP: El amor, la libertad y la religi\u00f3n, nunca se hab\u00edan llevado tan bien\" \/><meta itemprop=\"description\" content=\"Con motivo de su nueva gira por M\u00e9xico y Estados Unidos, conversamos con LP, una artista que no necesita presentaci\u00f3n, acerca del amor, la libertad y los fantasmas que nos persiguen en la vida disfrazados de religi\u00f3n. Checa nuestra pl\u00e1tica con Laura Pergolizzi y disfruta de toda su m\u00fasica en #ElBot\u00f3n\" \/><meta itemprop=\"uploadDate\" content=\"2022-04-12T22:22:40.000Z\" \/><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/s1.dmcdn.net\/v\/TqzcZ1YLVkmrm1Fux\/x120\" \/><meta itemprop=\"duration\" content=\"P317S\" \/><meta itemprop=\"embedUrl\" content=\"https:\/\/www.dailymotion.com\/embed\/video\/x89xswz\" \/><iframe loading=\"lazy\" style=\"width:100%;height:100%;position:absolute;left:0px;top:0px;overflow:hidden\" frameborder=\"0\" type=\"text\/html\" src=\"https:\/\/www.dailymotion.com\/embed\/video\/x89xswz?autoplay=1\" width=\"100%\" height=\"100%\"   allow=\"autoplay\" allowfullscreen><\/iframe><\/div>\n<p>El debate infinito acerca de la naturaleza del talento, si nace o se hace, podr\u00eda llevarnos a vagar en pensamientos por horas, pero cuando un artista pone sobre la mesa una capacidad creativa tan enorme, lo \u00fanico que queda por hacer, es cerrar los libros y apreciar en todo su esplendor sus habilidades.<\/p>\n<p>Es ah\u00ed cuando entendemos que si la m\u00fasica es parte de ti, se nota. Se traspira por cada poro y uno a uno tus sentidos seducen a quienes escuchan tus composiciones.<\/p>\n<p>Tomando esta premisa como base, nos topamos con Laura Pergolizzi, conocida en la escena musical como LP, la chica del cabello rizado y la voz s\u00faper poderosa. Una artista carism\u00e1tica que ha sabido construir su camino en la m\u00fasica al crear hits que de una u otra forma impactan a toda una generaci\u00f3n, adem\u00e1s de haber dejado un legado en la composici\u00f3n al escribir para artistas de la talla de Rihanna, los Backstreet Boys o Christina Aguilera.<\/p>\n<p>Una persona que desde muy peque\u00f1a entendi\u00f3 lo que quer\u00eda hacer con su vida, que tom\u00f3 la m\u00fasica como escape y la composici\u00f3n como amiga. Que nos ha regalado temas que perdurar\u00e1n por siempre y que m\u00e1s all\u00e1 de las melod\u00edas, nos hace conectar con un sentimiento \u00fanico que puede permanecer por mucho tiempo dentro de nosotros.<\/p>\n<p>Con el pretexto de su nueva gira por Estados Unidos y Latinoam\u00e9rica, donde ya agot\u00f3 las entradas, conversamos con LP acerca de sus sentimientos m\u00e1s arraigados, su postura ante la religi\u00f3n y esa creatividad innata que a\u00fan tiene para ofrecer dentro y fuera del escenario&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1323134\" data-permalink=\"https:\/\/elboton.com\/nacional\/entretenimiento\/entrevista-con-lp-el-amor-la-libertad-y-la-religion-nunca-se-habian-llevado-tan-bien\/attachment\/angels-cover-art283000x3000px_300dpi_rbg29\/\" data-orig-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg\" data-orig-size=\"1500,795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg?w=1024\" class=\"alignnone wp-image-1323134 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg?w=1024\" alt=\"\" width=\"1024\" height=\"543\" srcset=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg 1500w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg?resize=300,159 300w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg?resize=768,407 768w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg?resize=1024,543 1024w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg?resize=632,335 632w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg?resize=295,156 295w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>\u00bfC\u00f3mo te sientes de regresar a M\u00e9xico luego del Corona Capital del a\u00f1o pasado? Ahora ya est\u00e1 Churches (2021) en las calles&#8230;<\/strong><\/p>\n<p>En este momento, me siento un poco m\u00e1s conectada porque estamos en ensayos y todo, pero es raro lanzar un disco y no estar&#8230; o no estar de gira antes de que salga el disco, porque eso es lo normal. As\u00ed que s\u00ed, es un poco extra\u00f1o. Estoy muy emocionado de estar a punto de sacar este disco, de tocar este disco, finalmente.<\/p>\n<p><strong>Y en cuanto a un tour como este, con fechas y arenas enormes, \u00bfC\u00f3mo te preparas?<\/strong><\/p>\n<p>Tenemos un almac\u00e9n gigante, para traer todas nuestras luces y equipos y todo, y actuamos, y armamos el espect\u00e1culo con un md, es una jodida cosa. Pero es agradable.<\/p>\n<p>En cuanto al show, lo armamos con el directo. La banda se aprende las canciones, porque no se las saben todas de inmediato. Y luego hacemos las conexiones de las canciones, ya sabes, el setlist y todas estas cosas, es genial.<\/p>\n<p><iframe loading=\"lazy\" title=\"LP - Corona Capital 2021\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/YkCbxXltDII?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>Hablando un poco de Churches, adem\u00e1s de las claras referencias que haces a la religi\u00f3n, lo primero que percibo al escucharlo es amor. \u00bfPuedes contarme un poco acerca de los sentimientos que quisiste plasmar en \u00e9l?<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">En una palabra, amor, quiero decir, siempre trato de hacerme sentir algo, recordar algo, o convencerme o simplemente llegar a un acuerdo con algo, eso es lo m\u00e1s grande que trato de hacer. Y ni siquiera s\u00e9 si tratar es la palabra correcta porque no s\u00e9, solo me estoy expresando, solo estoy expresando un sentimiento para ser honesta, no es necesario nada loco.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es como un sentimiento que trato de sacar a la superficie y creo que la gente puede conectarse con eso. Saben de lo que hablo cuando lo digo. Estoy lista para hacer eso con todos, en persona ahora, quiero decir que el mundo est\u00e1 listo, supongo, sabes que lo pasamos mal. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Casi siento que no puedo creer que voy a estar de gira hasta que est\u00e9 realmente de gira.<\/span><\/p>\n<p><strong>\u00bfY la religi\u00f3n? \u00bfPor qu\u00e9 reflejarlo en tu disco, cu\u00e1l es tu postura ante Dios?<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Apenas creo en Dios, y quiero que todos adoren como quieran adorar, esa es la cuesti\u00f3n. Creo que Churches (2021), que el escenario que sucedi\u00f3 cuando yo fui a la iglesia y te cubr\u00edan la cabeza, no fue algo terrible, solo me hizo comenzar a pensar en c\u00f3mo eso era algo muy peque\u00f1o para que alguien te lo exigiera hacer, pero me hizo pensar en c\u00f3mo Dios quiere que actuemos, de todos modos, cubrirse la cabeza es algo peque\u00f1o, de hecho yo me cubr\u00ed la cabeza solo por diversi\u00f3n. Pero creo que todos deber\u00edan ser libres en el culto como quieran, y eso incluye a las personas que no me quieren en su iglesia tambi\u00e9n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Creo que si una religi\u00f3n quiere ser como&#8230; Crec\u00ed cat\u00f3lico, y cat\u00f3lico es el amor, la paz y la humanidad, \u00a1excepto si eres gay! Y no estoy tratando de matar a golpes la cosa gay. Honestamente, vete a la mierda. Me importa un carajo. Voy a ser gay te guste o no. Estar\u00e9 aqu\u00ed, teniendo sexo con personas del mismo sexo que yo, y no tienes que preocuparte, porque yo tampoco quiero o\u00edr hablar de tu vida sexual. Incluso si eres gay, me importa un carajo tu vida sexual. Ve, ve a ser gay tambi\u00e9n.<\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"LP - Angels (Official Music Video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/MBBJBhaeCX0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><span style=\"font-weight: 400;\">Tengo una relaci\u00f3n muy seria y hermosa, est\u00e1tica con Dios, y me pertenece, y no tengo que convencerte de eso, no me importa. Entonces, a cualquiera que le importe o piense que va a poner alg\u00fan tipo de idea en mi mierda, no va a suceder. Lo siento. Incluso puedes matarme y luego mis restos se ir\u00e1n y se convertir\u00e1n en otra persona. Y luego voy a encontrar una puta manera de hacerlo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Solo creo que se trata de libertad, la vida se trata de libertad y desafortunadamente es una de las cosas m\u00e1s dif\u00edciles de tener realmente a veces. Celebramos este pa\u00eds que somos tan afortunados. Vivo en este pa\u00eds con todas sus fallas, pero como hombre, deber\u00eda ser un regalo, y todav\u00eda no lo es. Y es tan jodidamente raro. Es alucinante.<\/span><\/p>\n<p><strong>Es una gran forma de pensar, y lo mejor es que esa libertad la plasmas en canciones poderosas&#8230; \u00bfCrees que tu sonido ha evolucionado gracias a esto o que tienes mayor libertad creativa?<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Puedo hablar mucho porque mi cuerpo es libre, pero la libertad est\u00e1 dentro de tu mente, as\u00ed que s\u00ed, mi esp\u00edritu se siente libre y trato de infundirme en mis canciones. No pienso en eso, pienso, escribo mucho sobre el amor rom\u00e1ntico, se siente bien. Si me miras y no crees que hago lo que me hace sentir bien, te est\u00e1s perdiendo el puto punto.<\/span><\/p>\n<p>\u00a1Me siento bien, huelo bien, me veo bien!<\/p>\n<p><strong>Seguramente te han preguntado en otro momento, pero siempre he querido saber \u00bfC\u00f3mo fue el momento, qu\u00e9 estabas haciendo cuando descubriste el poder de tu voz?<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Sol\u00eda \u200b\u200bcantar en el auto, ya sabes, en la parte trasera del auto, era una ni\u00f1a peque\u00f1a, y creo que mi hermano mayor me dec\u00eda &#8216;wow, suenas como la radio&#8217;, y yo dec\u00eda &#8216;\u00bfS\u00ed? &#8216; Estaba tan emocionada, y luego un d\u00eda mi mam\u00e1 estaba manejando y yo estaba cantando y ella dijo, baj\u00f3 el volumen de la radio y dijo&#8230; &#8216;\u00bfEres t\u00fa?&#8217; Porque era cantante, cantaba \u00f3pera y esas cosas cuando era joven. Entonces s\u00ed, recuerdo que hubo una reacci\u00f3n y hasta mi padre, que no era el m\u00e1s fan de la m\u00fasica, siempre quiso que yo cantara.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Luego comenc\u00e9 a cantar frente a los ni\u00f1os en la escuela. Era como una cosa en marcha. Y luego, cuando lleg\u00f3 el momento de hacer algo con mi vida, como un trabajo o como si todo fuera aburrido, no quise estar en la escuela. Ni siquiera s\u00e9 c\u00f3mo ser cantante o lo que eso implica. No conozco a nadie, no ten\u00eda nada. As\u00ed que me mud\u00e9 a la ciudad de Nueva York, consegu\u00ed un trabajo en un restaurante&#8230; y apest\u00e9 durante a\u00f1os, segu\u00ed adelante. Eso era mucho trabajo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Y pens\u00e9 la primera vez que abr\u00ed la boca en la ciudad de Nueva York en un escenario que alguien iba a correr hacia m\u00ed con el contrato discogr\u00e1fico. Y puedo ver eso en las personas cuando trabajo con j\u00f3venes a veces, puedo ver que a veces se sienten as\u00ed, y pienso: &#8216;No s\u00e9 cu\u00e1nto tiempo tomar\u00e1, pero tomar\u00e1 lo que sea necesario. Pero fue lo mejor que he hecho. Fue lo m\u00e1s dif\u00edcil y lo mejor. Creo que solo quer\u00eda hacer algo que fuera inconcebiblemente dif\u00edcil, \u00bfy adivinen qu\u00e9? Logr\u00e9 eso. Era inconcebiblemente duro, era la jodida cosa m\u00e1s dura.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero es tan gratificante que puedo cantarle canciones a la gente. Santa mierda. Guau.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1323136\" data-permalink=\"https:\/\/elboton.com\/nacional\/entretenimiento\/entrevista-con-lp-el-amor-la-libertad-y-la-religion-nunca-se-habian-llevado-tan-bien\/attachment\/promo-website-website-landscape-content-9\/\" data-orig-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Promo-Website-Website-landscape-content-9.jpeg\" data-orig-size=\"1500,1000\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Promo-Website-Website-landscape-content-9.jpeg?w=1024\" class=\"alignnone wp-image-1323136 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Promo-Website-Website-landscape-content-9.jpeg?w=1024\" alt=\"Promo Website Website Landscape Content 9\" width=\"1024\" height=\"683\" srcset=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Promo-Website-Website-landscape-content-9.jpeg 1500w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Promo-Website-Website-landscape-content-9.jpeg?resize=300,200 300w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Promo-Website-Website-landscape-content-9.jpeg?resize=768,512 768w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Promo-Website-Website-landscape-content-9.jpeg?resize=1024,683 1024w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Promo-Website-Website-landscape-content-9.jpeg?resize=503,335 503w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Promo-Website-Website-landscape-content-9.jpeg?resize=295,197 295w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>Qu\u00e9 incre\u00edble historia y s\u00faper interesante todo ese trabajo duro que hay detr\u00e1s&#8230;<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Solo lo digo porque vale la pena, pero a la gente le gusta ponerse a la defensiva. Casi se sienten avergonzados de decir que deseaban algo. Es algo as\u00ed como &#8216;S\u00ed, nunca tuve eso de todos modos, es porque no lo quise&#8217;. Llegas a ese punto en el que la gente est\u00e1 haciendo otras cosas y ganando dinero y todo eso, y dices &#8216;No siento que lo est\u00e9 logrando\u2019.<\/span><\/p>\n<p><strong>Antes de terminar me gustar\u00eda hablar un poco sobre M\u00e9xico y ese cari\u00f1o que tanto le tienes&#8230;<\/strong><\/p>\n<p>No, no, no fui yo. Pase lo que pase, no fui yo (risas).<\/p>\n<p><strong>Eres una experta de nuestra comida, lugares para visitar, nuestra cultura&#8230;<\/strong><\/p>\n<p>Hola, mi nombre es LP y soy un experto mexicano. \u00bfC\u00f3mo est\u00e1n? (risas).<\/p>\n<p><strong>Cuando no est\u00e1s en M\u00e9xico, \u00bfQu\u00e9 te hace pensar en nuestro pa\u00eds?<\/strong><\/p>\n<p>Tengo un hermoso ejemplo de eso, y ella viene aqu\u00ed a veces, todos los fines de semana&#8230; \u00a1Julieta Grajales!, ella me hace pensar en M\u00e9xico, obviamente. Tengo muchos amigos mexicanos y tengo un grupo de amigos de la Ciudad de M\u00e9xico que adoro. Pienso en vivir all\u00ed a veces, conseguir un lugar all\u00ed.<\/p>\n<p>Sabes que mi guitarrista es una mujer mexicana. Alejandra. Y es uno de mis lugares favoritos en el mundo, y lo ha sido durante muchos a\u00f1os. Y sigo acerc\u00e1ndome m\u00e1s y m\u00e1s a \u00e9l.<\/p>\n<p><strong>\u00bfAlguna comida o bar o alg\u00fan restaurante o algo que te guste mucho visitar cuando est\u00e1s aqu\u00ed?<\/strong><\/p>\n<p>Dios m\u00edo, pas\u00e9 el rato en Condesa, pero no recuerdo el nombre. Es mi lugar favorito de tacos, pero soy muy mala con los nombres, pero&#8230; \u00a1dime uno!<\/p>\n<p><strong>Mmmm \u00bfEl Vilsito?<\/strong><\/p>\n<p>\u00a1Ah\u00ed tienes! Jajaja. Hay un lugar que me encanta que est\u00e1 en una azotea al que siempre vamos.<\/p>\n<p><strong>\u00bfCon tacos?<\/strong><\/p>\n<p>Si, con bebidas, tacos y todo. Es muy buena comida, y est\u00e1 en una azotea. Creo que es en Condesa. Oh, Dios m\u00edo, extra\u00f1o esos d\u00edas, cuando iba a ver a mi amigo Bernardo y todos nuestros amigos all\u00e1. Era un barrio realmente genial que ahora no puedo recordar porque soy muy mala con cosas como esa.<\/p>\n<p>Pero siempre \u00edbamos all\u00ed para grabar este lugar incre\u00edble, hab\u00eda muchos lugares que se derraman en la calle. Hay un piso de arriba, tan jodidamente enfermo.<\/p>\n<p><iframe loading=\"lazy\" title=\"LP - Lost On You (Official Music Video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/hn3wJ1_1Zsg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El debate infinito acerca de la naturaleza del talento, si nace o se hace, podr\u00eda llevarnos a vagar en pensamientos por horas, pero cuando un artista pone sobre la mesa una capacidad creativa tan enorme, lo \u00fanico que queda por hacer, es cerrar los libros y apreciar en todo su esplendor sus habilidades. Es ah\u00ed [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1323134,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[1262],"tags":[1237,1236],"genre":[],"internal":[],"class_list":["post-1323447","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-videos","tag-churches","tag-lp","post_format-post-format-video","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n - El Bot\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El debate infinito acerca de la naturaleza del talento, si nace o se hace, podr\u00eda llevarnos a vagar en pensamientos por horas, pero cuando un artista pone sobre la mesa una capacidad creativa tan enorme, lo \u00fanico que queda por hacer, es cerrar los libros y apreciar en todo su esplendor sus habilidades. Es ah\u00ed [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-30T21:18:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-12T22:24:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"795\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n\",\"datePublished\":\"2022-03-30T21:18:55+00:00\",\"dateModified\":\"2022-04-12T22:24:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/\"},\"wordCount\":1921,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg\",\"keywords\":[\"Churches\",\"LP\"],\"articleSection\":[\"Videos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/\",\"url\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/\",\"name\":\"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg\",\"datePublished\":\"2022-03-30T21:18:55+00:00\",\"dateModified\":\"2022-04-12T22:24:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg\",\"width\":1500,\"height\":795},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/elboton.com\/nacional\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n - El Bot\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n - El Bot\u00f3n","og_description":"El debate infinito acerca de la naturaleza del talento, si nace o se hace, podr\u00eda llevarnos a vagar en pensamientos por horas, pero cuando un artista pone sobre la mesa una capacidad creativa tan enorme, lo \u00fanico que queda por hacer, es cerrar los libros y apreciar en todo su esplendor sus habilidades. Es ah\u00ed [&hellip;]","og_url":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2022-03-30T21:18:55+00:00","article_modified_time":"2022-04-12T22:24:02+00:00","og_image":[{"width":1500,"height":795,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg","type":"image\/jpeg"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n","datePublished":"2022-03-30T21:18:55+00:00","dateModified":"2022-04-12T22:24:02+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/"},"wordCount":1921,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg","keywords":["Churches","LP"],"articleSection":["Videos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/","url":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/","name":"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg","datePublished":"2022-03-30T21:18:55+00:00","dateModified":"2022-04-12T22:24:02+00:00","breadcrumb":{"@id":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg","width":1500,"height":795},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/elboton.com\/nacional\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/elboton.com\/nacional\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\u00f3n","url":"http:\/\/elboton.com\/nacional\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/nacional\/videos\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg"},"articleSection":"Videos","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["churches","lp"],"dateCreated":"2022-03-30T21:18:55Z","datePublished":"2022-03-30T21:18:55Z","dateModified":"2022-04-12T22:24:02Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Entrevista con LP: los fantasmas que nos persiguen disfrazados de religi\\u00f3n\",\"url\":\"http:\\\/\\\/elboton.com\\\/nacional\\\/videos\\\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/nacional\\\/videos\\\/entrevista-con-lp-los-fantasmas-que-nos-persiguen-disfrazados-de-religion\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/03\\\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/03\\\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg\"},\"articleSection\":\"Videos\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"churches\",\"lp\"],\"dateCreated\":\"2022-03-30T21:18:55Z\",\"datePublished\":\"2022-03-30T21:18:55Z\",\"dateModified\":\"2022-04-12T22:24:02Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/03\/Angels-Cover-Art25283000x3000px_300dpi_RBG2529-e1648499963828.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/posts\/1323447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/comments?post=1323447"}],"version-history":[{"count":1,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/posts\/1323447\/revisions"}],"predecessor-version":[{"id":1323449,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/posts\/1323447\/revisions\/1323449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/media\/1323134"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/media?parent=1323447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/categories?post=1323447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/tags?post=1323447"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/genre?post=1323447"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/nacional\/wp-json\/wp\/v2\/internal?post=1323447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}