{"id":1336681,"date":"2023-03-02T16:40:05","date_gmt":"2023-03-03T00:40:05","guid":{"rendered":"https:\/\/elboton.com\/?p=1336681"},"modified":"2023-03-02T16:40:05","modified_gmt":"2023-03-03T00:40:05","slug":"por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales","status":"publish","type":"post","link":"https:\/\/elboton.com\/stockton-modesto\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/","title":{"rendered":"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales?"},"content":{"rendered":"<p>Aunque muchos no lo han notado, el colombiano J Balvin tiene algunos meses que est\u00e1 fuera del ojo p\u00fablico e incluso fuera de redes sociales como Instagram en donde estaba activo todo el tempo.<\/p>\n<p>La \u00faltima publicaci\u00f3n del cantante fue hecha en septiembre y se trata de un post en el que est\u00e1 sonriendo con su beb\u00e9 R\u00edo a quien tuvo hace tiempo con su pareja, la modelo argentina Valentina Ferrer. Por otro lado, el \u00faltimo tema que Balvin solt\u00f3 fue &#8216;Nivel De Perreo&#8217;, un track junto a Ryan Castro lanzado en junio.<\/p>\n<p>Aunque todo el tiempo es captado en eventos, galas, premiaciones y ceremonias, el cantante de 37 a\u00f1os ha dejado la vida p\u00fablica desde hace tiempo y sus fans no saben por qu\u00e9 fue que tom\u00f3 esta decisi\u00f3n.<\/p>\n<p>Fue durante una reciente entrevista que el colombiano dio una explicaci\u00f3n acerca de esto y es que la principal raz\u00f3n por la que Balvin ha tenido lejan\u00eda de la vida p\u00fablica, es porque est\u00e1 centrado en su familia y en el amor para darles, por lo que dej\u00f3 de lado los lujos y la excentricidad que mostraba d\u00eda a d\u00eda en sus redes sociales.<\/p>\n<p>Seg\u00fan lo que coment\u00f3 Jos\u00e9 \u00c1lvaro Osorio Balvin para Billboard, esta decisi\u00f3n ha sido muy positiva en su vida e incluso le ha ayudado a vivir m\u00e1s el presente: &#171;Obviamente echo de menos a mis fans, pero cuando sea el momento adecuado volver\u00e9&#187;, comparti\u00f3.<\/p>\n<p>Fue a mitad del 2022 que Balvin pospuso su gira Jos\u00e9 US la cual contaba con 25 fechas cerradas, mencionando que se trataba de problemas t\u00e9cnicos y &#171;desaf\u00edos de producci\u00f3n&#187;, sin embargo se le vio en diversas premiaciones e incluso lanz\u00f3 su colaboraci\u00f3n con Nike para sus tenis los Air Balvin Jordan 2.<\/p>\n<p>Otro de los temas por los cuales Balvin no est\u00e1 dispuesto a hacer m\u00fasica, es que seg\u00fan \u00e9l a\u00fan no cuenta con un concepto que poner en un disco, por lo que est\u00e1 esperando la inspiraci\u00f3n para volver a darles algo bueno a sus fans: &#171;He hecho m\u00fasica para pasarla bien como siempre. Todav\u00eda no tengo un concepto, no tengo un \u00e1lbum por hacer. Pero es porque quiero tener un concepto claro, diferente y fresco. Posiblemente en estos d\u00edas la musa llega y me viene el concepto y de ah\u00ed nace un \u00e1lbum. Puede ser este a\u00f1o o el pr\u00f3ximo&#187;, concluy\u00f3.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Ci0Uj03vSgG\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:500px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/Ci0Uj03vSgG\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/Ci0Uj03vSgG\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by J Balvin (@jbalvin)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque muchos no lo han notado, el colombiano J Balvin tiene algunos meses que est\u00e1 fuera del ojo p\u00fablico e incluso fuera de redes sociales como Instagram en donde estaba activo todo el tempo. La \u00faltima publicaci\u00f3n del cantante fue hecha en septiembre y se trata de un post en el que est\u00e1 sonriendo con [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1336683,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[691,1189],"tags":[975,1024,1941],"genre":[],"internal":[],"class_list":["post-1336681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-musica","tag-instagram","tag-j-balvin","tag-redes-sociales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales? - El Bot\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales? - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Aunque muchos no lo han notado, el colombiano J Balvin tiene algunos meses que est\u00e1 fuera del ojo p\u00fablico e incluso fuera de redes sociales como Instagram en donde estaba activo todo el tempo. La \u00faltima publicaci\u00f3n del cantante fue hecha en septiembre y se trata de un post en el que est\u00e1 sonriendo con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-03T00:40:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/SEO-Image-1200x675-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales?\",\"datePublished\":\"2023-03-03T00:40:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/\"},\"wordCount\":454,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg\",\"keywords\":[\"Instagram\",\"J Balvin\",\"Redes Sociales\"],\"articleSection\":[\"Entretenimiento\",\"M\u00fasica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/\",\"url\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/\",\"name\":\"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales? - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg\",\"datePublished\":\"2023-03-03T00:40:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg\",\"width\":4924,\"height\":2745,\"caption\":\"Fotograf\u00eda: Getty Images.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/elboton.com\/stockton-modesto\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales? - El Bot\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales? - El Bot\u00f3n","og_description":"Aunque muchos no lo han notado, el colombiano J Balvin tiene algunos meses que est\u00e1 fuera del ojo p\u00fablico e incluso fuera de redes sociales como Instagram en donde estaba activo todo el tempo. La \u00faltima publicaci\u00f3n del cantante fue hecha en septiembre y se trata de un post en el que est\u00e1 sonriendo con [&hellip;]","og_url":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2023-03-03T00:40:05+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/SEO-Image-1200x675-1.png","type":"image\/png"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales?","datePublished":"2023-03-03T00:40:05+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/"},"wordCount":454,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg","keywords":["Instagram","J Balvin","Redes Sociales"],"articleSection":["Entretenimiento","M\u00fasica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/","url":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/","name":"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales? - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg","datePublished":"2023-03-03T00:40:05+00:00","breadcrumb":{"@id":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg","width":4924,"height":2745,"caption":"Fotograf\u00eda: Getty Images."},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales?"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/elboton.com\/stockton-modesto\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/elboton.com\/stockton-modesto\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPor qu\u00e9 J Balvin se alej\u00f3 de la m\u00fasica y las redes sociales?","url":"http:\/\/elboton.com\/stockton-modesto\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/stockton-modesto\/entretenimiento\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg"},"articleSection":"M\u00fasica","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["instagram","j balvin","redes sociales"],"dateCreated":"2023-03-03T00:40:05Z","datePublished":"2023-03-03T00:40:05Z","dateModified":"2023-03-03T00:40:05Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPor qu\\u00e9 J Balvin se alej\\u00f3 de la m\\u00fasica y las redes sociales?\",\"url\":\"http:\\\/\\\/elboton.com\\\/stockton-modesto\\\/entretenimiento\\\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/stockton-modesto\\\/entretenimiento\\\/por-que-j-balvin-se-alejo-de-la-musica-y-las-redes-sociales\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/GettyImages-1457416586-e1677803986787.jpg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/GettyImages-1457416586-e1677803986787.jpg\"},\"articleSection\":\"M\\u00fasica\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"instagram\",\"j balvin\",\"redes sociales\"],\"dateCreated\":\"2023-03-03T00:40:05Z\",\"datePublished\":\"2023-03-03T00:40:05Z\",\"dateModified\":\"2023-03-03T00:40:05Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/03\/GettyImages-1457416586-e1677803986787.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1336681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1336681"}],"version-history":[{"count":1,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1336681\/revisions"}],"predecessor-version":[{"id":1336684,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1336681\/revisions\/1336684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/media\/1336683"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1336681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1336681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1336681"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/genre?post=1336681"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/internal?post=1336681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}