{"id":1349982,"date":"2024-04-11T13:52:58","date_gmt":"2024-04-11T20:52:58","guid":{"rendered":"https:\/\/elboton.com\/?p=1349982"},"modified":"2024-04-11T13:52:58","modified_gmt":"2024-04-11T20:52:58","slug":"entrevista-con-ysrael-barajas-la-casa-siempre-gana","status":"publish","type":"post","link":"https:\/\/elboton.com\/stockton-modesto\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/","title":{"rendered":"Entrevista con Ysrael Barajas: La casa siempre gana"},"content":{"rendered":"<p>Ahora todos quieren ser b\u00e9licos pero a pocos les queda, todos quieren hacer corridos pero solo unos tienen lo que se necesita. Mucha actitud, andar tumbado y tirar mucho flow, tres indispensables para vivir como capo.<\/p>\n<p>Ysrael Barajas lo tiene todo y juega en su propia cancha. Hace corridos porque lo lleva en la sangre y representa a su natal Tijuana con un sonido totalmente distinto a lo que has escuchado.<\/p>\n<p>Basta con pasarse por su canal de YouTube para quedarse apreciando todo lo que ha sacado. Su propuesta en temas como &#8216;GPI&#8217; o &#8216;Bel Beli&#8217; es contundente. Ysra no viene a ser uno m\u00e1s en el movimiento, viene a darlo todo y a comerse la escena.<\/p>\n<p>Con tan poco tiempo lanzando m\u00fasica ya cuenta con m\u00e1s de 1.7 millones de escuchas, lo que nos da una idea de hasta d\u00f3nde llegar\u00e1 su carrera. Ya est\u00e1 firmado en la disquera m\u00e1s grande del mundo y es amigo de los grandes del g\u00e9nero, su subida es imparable y su nuevo disco est\u00e1 por escucharse en todos lados.<\/p>\n<p>Hace unos d\u00edas tuve el gusto de conversar con \u00e9l sobre la vida de rockstar y los corridos tumbados. Me explic\u00f3 lo que es ser un aluc\u00edn y c\u00f3mo ha creado electrocorridos desde cero. Un pionero del g\u00e9nero y un crack en toda la extensi\u00f3n de la palabra.<\/p>\n<p>Hazte un favor y corre a escuchar su propuesta pues es uno de los primeros en crear esta m\u00fasica y acaba de lanzar su nuevo \u00e1lbum La Casa Siempre Gana, una joyita que no debes dejar pasar.<\/p>\n<p><iframe loading=\"lazy\" title=\"Ysrael Barajas, Miranda Le\u00f3n - Beli Beli (Video Oficial)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/IUHUUBtwezk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>Primero que nada, me gustar\u00eda empezar justo con el disco, platicar un poquito de &#8216;La Casa Siempre Gana&#8217; y que me cuentes un poquito de cu\u00e1l es ese mensaje que quer\u00edas compartir con el p\u00fablico&#8230;<\/strong><\/p>\n<p>Pues m\u00e1s que nada gana, &#8216;La Casa Siempre Gana&#8217; fue derivada del casino, un tema del casino, eso y mi apellido y aparte es una frase como muy de impacto porque al final de cuentas, aunque pierda, siempre gano porque aprendo de lo bueno y de lo malo.<\/p>\n<p>Siempre he buscado motivar a la gente con mis letras, que es una forma de darles un ejemplo bueno y de dejarles una ense\u00f1anza en mis canciones, aunque relaten algo de lo que es el mundo del narcotr\u00e1fico, siempre en todas las canciones es una ense\u00f1anza, porque al final de cuentas esas personas tambi\u00e9n son personas y tambi\u00e9n tuvieron sue\u00f1os, tienen sue\u00f1os y se enfocan en los suyos para seguir avanzando.<\/p>\n<p><strong>Se me hace bien curioso como pudiste hacer una rola de algo que no existe, o sea alguien que hace rock tiene influencias de rock o alguien que hace rap, tiene un mont\u00f3n de raperos en quienes inspirarse, pero algo que no existe es el electro corrido y t\u00fa hiciste ya algunas rolas as\u00ed, \u00bfC\u00f3mo creaste este sonido?<\/strong><\/p>\n<p>La de &#8216;Beli Beli&#8217; es como tipo dance pop. Yo siempre he sido as\u00ed como de que me gusta experimentar mucho y he sido como muy vers\u00e1til en ese aspecto. La tonada la hice con pura guitarra y se la mand\u00e9 a un productor de Guadalajara, le dije que era algo para hacer con esta persona, con Miranda, en ese tiempo no \u00e9ramos nada, entonces se la mand\u00e9 y le mand\u00e9 la propuesta a Miranda y le gust\u00f3.<\/p>\n<p>Trabajamos muy muy c\u00f3modos. Creo que como en una semana ya estaban las voces de ella, voces m\u00edas y ya en dos semanas m\u00e1s grabamos el video. Todo muy r\u00e1pido y muy contentos de que a la gente le haya gustado. Creo que es una canci\u00f3n buena y pegajosa tambi\u00e9n.<\/p>\n<p><strong>Por ah\u00ed tambi\u00e9n tienes otro tema en el disco que se llama &#8216;GPI&#8217; que ya tiene 12 millones de reproducciones en YouTube, algo bestial&#8230;<\/strong><\/p>\n<p>Esperaba que le fuera bien, pero no tanto. Cada d\u00eda sube de vistas y buenas vistas y eso es muy bonito. Es muy curioso tambi\u00e9n ver como tienes una canci\u00f3n y no dimensionas que puede llegar a tanto, pero creo que es una canci\u00f3n que se va a quedar siempre en mi carrera, siento que va a marcar mucho.<\/p>\n<p>Entonces muy contentos porque esa canci\u00f3n sali\u00f3 as\u00ed de espont\u00e1neo en la casa est\u00e1bamos as\u00ed dos camaradas y yo. Uno toca la guitarra entonces le dije &#8216;Hay que hacer una rola ahorita&#8217;\u00a0 entonces ya mi camarada empez\u00f3 a tocar la guitarra, le dije &#8216;Agarremos un tono menor&#8217; y ya se fue dando as\u00ed solo. Fue algo que sali\u00f3 r\u00e1pido, en 30 minutos.<\/p>\n<p>Dije &#8216;Vamos a grabar un TikTok&#8217;, lo sub\u00ed, peg\u00f3 el TikTok y pues nom\u00e1s faltaba ver cu\u00e1ndo la pod\u00eda soltar.<\/p>\n<p><iframe loading=\"lazy\" title=\"Ysrael Barajas - GPI (Video Oficial)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/gFOiW8evTRQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>\u00bfY c\u00f3mo se te ocurri\u00f3 darle la vuelta y meterle el punch de un beat de electr\u00f3nica?<\/strong><\/p>\n<p>No s\u00e9, fue todo bien curioso porque yo se la mand\u00e9 al productor y le dije &#8216;Quiero que al final truene as\u00ed como para un antro&#8217;. Le mand\u00e9 varios ejemplos y dijo &#8216;A ver qu\u00e9 puedo hacer&#8217;. Era raro porque toda la canci\u00f3n es guitarra, muy muy mexicano, todo muy regional, entonces me gust\u00f3 esa combinaci\u00f3n. No s\u00e9 ni por qu\u00e9 se la met\u00ed, pero fue algo as\u00ed que se me ocurri\u00f3 de una. Dije &#8216;Voy a meter algo diferente a esta canci\u00f3n&#8217; y a mucha gente no le gust\u00f3, pero a mucha otra s\u00ed.<\/p>\n<p>A la gente que no le gustan los corridos, cuando escuchan esa parte es como &#8216;\u00bfEst\u00e1 qu\u00e9 rollo?&#8217;, y ya se quedan por morbo, por curiosidad.<\/p>\n<p><strong>\u00bfQu\u00e9 piensas del cambio que est\u00e1 viviendo la m\u00fasica en el que ya no hay una barrera entre g\u00e9neros y que un artista puede hacer lo que quiera?<\/strong><\/p>\n<p>Est\u00e1 bien, al final de cuentas la m\u00fasica siempre va evolucionando y la gente tiene que ir evolucionando con ella. Es muy relativa esa frase porque pues cada quien lo toma diferente. Siento que la gente tiene que ir cambiando ese chip, a veces siento que la gente mayor ya no lo puede cambiar pero otras no s\u00e9, porque incluso hay gente mayor que s\u00ed le gusta ese rollo nuevo.<\/p>\n<p>Al final de cuentas hay de corridos a corridos, pero s\u00ed, ir evolucionando nosotros juntos con la m\u00fasica nueva que va saliendo, porque al final de cuentas es algo que no vamos a poder cambiar y es algo que que siempre va a estar, entonces adaptarnos y aceptarlo.<\/p>\n<p><strong>\u00bfCrees que M\u00e9xico o la m\u00fasica mexicana est\u00e1 en su prime?<\/strong><\/p>\n<p>S\u00ed, obviamente la m\u00fasica mexicana ahorita llega a lugares que jam\u00e1s cre\u00edmos, Grammys, Billboards, es impresionante. La m\u00fasica mexicana ha abierto otros panoramas y los artistas ahorita que est\u00e1n representando la neta qu\u00e9 curada, qu\u00e9 bien por ellos. Es una forma de que el mundo voltee a ver a M\u00e9xico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1350045\" data-permalink=\"https:\/\/elboton.com\/stockton-modesto\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/attachment\/yb-48\/\" data-orig-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg\" data-orig-size=\"4160,6240\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 6D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1706896528&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;61&quot;,&quot;iso&quot;:&quot;1000&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg?w=683\" class=\"alignnone wp-image-1350045 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg?w=683\" alt=\"Yb (48)\" width=\"683\" height=\"1024\" srcset=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg 4160w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg?resize=200,300 200w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg?resize=768,1152 768w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg?resize=683,1024 683w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg?resize=1024,1536 1024w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg?resize=1365,2048 1365w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg?resize=223,335 223w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-48.jpg?resize=253,380 253w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<p><strong>Mucho de lo que reflejan los artistas del momento, quiz\u00e1 incluy\u00e9ndote, es una vida de lujos, de joyas, de marcas, de fiestas, de vida nocturna, \u00bfC\u00f3mo es la vida de un artista como t\u00fa?<\/strong><\/p>\n<p>Pues tiene sus pros y sus contras, porque al final de cuentas al ser una figura p\u00fablica entre comillas, tienes la tensi\u00f3n y los ojos de m\u00e1s gente, entonces si tu estilo de vida o tu carrera llega a ojos equivocados, puede que te vean ya con malicia, con maldad de que &#8216;este este morro tiene dinero&#8217;. M\u00e1s ac\u00e1 en Tijuana, ac\u00e1 como que se da mucho, entonces s\u00ed hay que cuidarse un poquito m\u00e1s.<\/p>\n<p>Por el otro lado es bonito si te gusta porque no lo ves como trabajo. El otro d\u00eda vi una frase que dec\u00eda, &#171;Pas\u00f3 el tiempo y no nos dimos cuenta de que ya estamos viviendo ese alg\u00fan d\u00eda&#187;.\u00a0 Y es cierto, yo dec\u00eda, alg\u00fan d\u00eda voy a tener tal carro y ahorita lo tienes y como que tu cabeza no lo procesa, como que vas avanzando en autom\u00e1tico y la vives y la debes. Si no te das un tiempo para decir, &#8216;Estoy parado aqu\u00ed, ya hice esto, cosas que antes ve\u00eda muy lejanas&#8217; se pasa.<\/p>\n<p>Es bonito cuando vas cumpliendo metas tanto personales como en el mundo. No todo es fiesta, no todo es lo que era. Bueno, te lo digo yo personalmente, porque ya ahorita ya estoy con mi pareja y como que ya me calm\u00e9 un poquito m\u00e1s, estoy m\u00e1s centrado, estoy madurando en ciertos aspectos, tanto musicales, tanto compartiendo mi vida con esa persona y es bonito.<\/p>\n<p>Ahorita estoy en una etapa de mi vida muy buena. S\u00ed hubo un tiempo y te lo voy a confesar, en el que siento que me estaba descarrilando, me estaba descarrilando porque al final de cuentas pues tengo 22 a\u00f1os, estoy morro todav\u00eda y a veces no medimos las cosas, hacemos cosas muy tontas, muy por dejarnos llevar por el momento y al final de cuentas est\u00e1s mal pero al final de cuentas aprendes. Al principio aprendes y vas aprendiendo de cada tropiezo que tienes, de cada fallo que haces, aunque en su momento no lo entiendas, pero s\u00ed aprendes, se aprende de todo.<\/p>\n<p><strong>Hay un concepto que quiz\u00e1 mucha gente no entiende al 100, hasta yo me llego a incluir, pero seguramente t\u00fa nos podr\u00e1s ayudar much\u00edsimo. \u00bfQu\u00e9 es se un aluc\u00edn?<\/strong><\/p>\n<p>F\u00edjate que el otro d\u00eda lo estaba platicando con mi novia porque ella tiene un concepto y yo tengo otro. Ella dice que aluc\u00edn, es andar de b\u00e9lico, andar as\u00ed con armas y yo lo tomo como la palabra de que est\u00e1s alucinando, est\u00e1s viviendo en una vida que no tienes, est\u00e1s aparentando algo que no eres.<\/p>\n<p>Ese es mi concepto de aluc\u00edn, porque est\u00e1s alucinando de que eres y no eres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ahora todos quieren ser b\u00e9licos pero a pocos les queda, todos quieren hacer corridos pero solo unos tienen lo que se necesita. Mucha actitud, andar tumbado y tirar mucho flow, tres indispensables para vivir como capo. Ysrael Barajas lo tiene todo y juega en su propia cancha. Hace corridos porque lo lleva en la sangre [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1350044,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[691,1189],"tags":[1016,2726,2730,1230,2729,2727,1229,2038,2728,1033,2725],"genre":[],"internal":[],"class_list":["post-1349982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-musica","tag-album","tag-alucin","tag-beli-beli","tag-corridos-tumbados","tag-gpi","tag-la-casa-siempre-gana","tag-natanael-cano","tag-peso-pluma","tag-sony-music","tag-tijuana","tag-ysrael-barajas","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrevista con Ysrael Barajas: La casa siempre gana - El Bot\u00f3n<\/title>\n<meta name=\"description\" content=\"Platicamos con Ysrael Barajas sobre su nuevo \u00e1lbum La Casa Siempre Gana, los electro corridos, la escena en Tijuana y ser un aluc\u00edn.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista con Ysrael Barajas: La casa siempre gana - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Platicamos con Ysrael Barajas sobre su nuevo \u00e1lbum La Casa Siempre Gana, los electro corridos, la escena en Tijuana y ser un aluc\u00edn.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-11T20:52:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/SEO-Image-1200x675-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Entrevista con Ysrael Barajas: La casa siempre gana\",\"datePublished\":\"2024-04-11T20:52:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/\"},\"wordCount\":1701,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg\",\"keywords\":[\"\u00c1lbum\",\"Aluc\u00edn\",\"Beli Beli\",\"Corridos Tumbados\",\"GPI\",\"La Casa Siempre Gana\",\"Natanael Cano\",\"Peso Pluma\",\"Sony Music\",\"Tijuana\",\"Ysrael Barajas\"],\"articleSection\":[\"Entretenimiento\",\"M\u00fasica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/\",\"url\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/\",\"name\":\"Entrevista con Ysrael Barajas: La casa siempre gana - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg\",\"datePublished\":\"2024-04-11T20:52:58+00:00\",\"description\":\"Platicamos con Ysrael Barajas sobre su nuevo \u00e1lbum La Casa Siempre Gana, los electro corridos, la escena en Tijuana y ser un aluc\u00edn.\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg\",\"width\":4159,\"height\":3213,\"caption\":\"Fotograf\u00eda: Sony Music Latin.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista con Ysrael Barajas: La casa siempre gana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/elboton.com\/stockton-modesto\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista con Ysrael Barajas: La casa siempre gana - El Bot\u00f3n","description":"Platicamos con Ysrael Barajas sobre su nuevo \u00e1lbum La Casa Siempre Gana, los electro corridos, la escena en Tijuana y ser un aluc\u00edn.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista con Ysrael Barajas: La casa siempre gana - El Bot\u00f3n","og_description":"Platicamos con Ysrael Barajas sobre su nuevo \u00e1lbum La Casa Siempre Gana, los electro corridos, la escena en Tijuana y ser un aluc\u00edn.","og_url":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2024-04-11T20:52:58+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/SEO-Image-1200x675-1.png","type":"image\/png"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Entrevista con Ysrael Barajas: La casa siempre gana","datePublished":"2024-04-11T20:52:58+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/"},"wordCount":1701,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg","keywords":["\u00c1lbum","Aluc\u00edn","Beli Beli","Corridos Tumbados","GPI","La Casa Siempre Gana","Natanael Cano","Peso Pluma","Sony Music","Tijuana","Ysrael Barajas"],"articleSection":["Entretenimiento","M\u00fasica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/","url":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/","name":"Entrevista con Ysrael Barajas: La casa siempre gana - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg","datePublished":"2024-04-11T20:52:58+00:00","description":"Platicamos con Ysrael Barajas sobre su nuevo \u00e1lbum La Casa Siempre Gana, los electro corridos, la escena en Tijuana y ser un aluc\u00edn.","breadcrumb":{"@id":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg","width":4159,"height":3213,"caption":"Fotograf\u00eda: Sony Music Latin."},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"Entrevista con Ysrael Barajas: La casa siempre gana"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/elboton.com\/stockton-modesto\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/elboton.com\/stockton-modesto\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Entrevista con Ysrael Barajas: La casa siempre gana","url":"http:\/\/elboton.com\/stockton-modesto\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/stockton-modesto\/entretenimiento\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg"},"articleSection":"M\u00fasica","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["\u00e1lbum","aluc\u00edn","beli beli","corridos tumbados","gpi","la casa siempre gana","natanael cano","peso pluma","sony music","tijuana","ysrael barajas"],"dateCreated":"2024-04-11T20:52:58Z","datePublished":"2024-04-11T20:52:58Z","dateModified":"2024-04-11T20:52:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Entrevista con Ysrael Barajas: La casa siempre gana\",\"url\":\"http:\\\/\\\/elboton.com\\\/stockton-modesto\\\/entretenimiento\\\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/stockton-modesto\\\/entretenimiento\\\/entrevista-con-ysrael-barajas-la-casa-siempre-gana\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/YB-68-e1712868751393.jpg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/YB-68-e1712868751393.jpg\"},\"articleSection\":\"M\\u00fasica\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"\\u00e1lbum\",\"aluc\\u00edn\",\"beli beli\",\"corridos tumbados\",\"gpi\",\"la casa siempre gana\",\"natanael cano\",\"peso pluma\",\"sony music\",\"tijuana\",\"ysrael barajas\"],\"dateCreated\":\"2024-04-11T20:52:58Z\",\"datePublished\":\"2024-04-11T20:52:58Z\",\"dateModified\":\"2024-04-11T20:52:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2024\/04\/YB-68-e1712868751393.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1349982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1349982"}],"version-history":[{"count":2,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1349982\/revisions"}],"predecessor-version":[{"id":1350046,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1349982\/revisions\/1350046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/media\/1350044"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1349982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1349982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1349982"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/genre?post=1349982"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/stockton-modesto\/wp-json\/wp\/v2\/internal?post=1349982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}