{"id":1322438,"date":"2022-02-21T12:04:26","date_gmt":"2022-02-21T20:04:26","guid":{"rendered":"https:\/\/elboton.com\/?p=1322438"},"modified":"2022-02-21T12:15:21","modified_gmt":"2022-02-21T20:15:21","slug":"christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda","status":"publish","type":"post","link":"https:\/\/elboton.com\/ventura\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/","title":{"rendered":"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda"},"content":{"rendered":"<p>Tras un a\u00f1o y medio de relaci\u00f3n, Belinda y Christian Nodal anunciaron hace una semana, que hab\u00edan puesto punto final a su noviazgo y que seguir\u00edan por caminos separados. En medio de los rumores sobre las razones de su rompimiento, muchos han preguntado qu\u00e9 pasar\u00e1 con los tatuajes que se hizo el int\u00e9rprete de \u2018Adi\u00f3s Amor\u2019 en honor a su ex.<\/p>\n<p>Aunque muchos desean que exista una reconciliaci\u00f3n, la realidad es que esta no se ve nada cerca, pues el cantante del regional mexicano ya tom\u00f3 cartas en el asunto y se deshizo de uno de los tatuajes que ten\u00eda en su rostro. Cerca de la oreja derecha llevaba el nombre de su expareja, &#171;Beli&#187;, pero ahora lo ha cambiado por los cuatro palos de p\u00f3ker: pica, coraz\u00f3n, rombo y tr\u00e9bol.<\/p>\n<p>Durante el fin de semana, el cantante de 23 a\u00f1os reapareci\u00f3 ante el p\u00fablico y ofreci\u00f3 un concierto en Costa Rica, donde dej\u00f3 ver el cambio que se hizo en su cara. Fue el fot\u00f3grafo David Chac\u00f3n quien captur\u00f3 las im\u00e1genes en las que se ve el tatuaje modificado.<\/p>\n<p>Pero la palabra \u201cBeli\u201d no es el \u00fanico tatuaje que Christian se hizo por su ex. Al artista se le conocen otras dos marcas que se hizo para demostrarle su amor a quien \u00e9l crey\u00f3 que se convertir\u00eda en su esposa. En su frente llevaba la palabra &#171;Utop\u00eda&#187;, el nombre de un \u00e1lbum musical de Belinda, y en el pecho se tatu\u00f3 sus ojos.<\/p>\n<p>Durante su noviazgo, Belinda tambi\u00e9n le demostr\u00f3 su amor con un tatuaje. Se realiz\u00f3 un coraz\u00f3n que encierra las iniciales de su ahora ex prometido &#171;CN&#187;.<\/p>\n<p>Hasta el momento se desconoce si Belinda y Christian Nodal decidir\u00e1n retirarse los dem\u00e1s tatuajes que llevan en su piel.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1322446\" data-permalink=\"https:\/\/elboton.com\/ventura\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/attachment\/captura-de-pantalla-2022-02-21-141257\/\" data-orig-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/Captura-de-pantalla-2022-02-21-141257-e1645474509786.jpg\" data-orig-size=\"1202,741\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/Captura-de-pantalla-2022-02-21-141257-e1645474509786.jpg?w=1024\" class=\"alignnone wp-image-1322446 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/Captura-de-pantalla-2022-02-21-141257-e1645474509786.jpg?w=1024\" alt=\"Captura De Pantalla 2022 02 21 141257\" width=\"1024\" height=\"631\" srcset=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/Captura-de-pantalla-2022-02-21-141257-e1645474509786.jpg 1202w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/Captura-de-pantalla-2022-02-21-141257-e1645474509786.jpg?resize=300,185 300w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/Captura-de-pantalla-2022-02-21-141257-e1645474509786.jpg?resize=768,473 768w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/Captura-de-pantalla-2022-02-21-141257-e1645474509786.jpg?resize=1024,631 1024w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/Captura-de-pantalla-2022-02-21-141257-e1645474509786.jpg?resize=543,335 543w, https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/Captura-de-pantalla-2022-02-21-141257-e1645474509786.jpg?resize=295,182 295w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras un a\u00f1o y medio de relaci\u00f3n, Belinda y Christian Nodal anunciaron hace una semana, que hab\u00edan puesto punto final a su noviazgo y que seguir\u00edan por caminos separados. En medio de los rumores sobre las razones de su rompimiento, muchos han preguntado qu\u00e9 pasar\u00e1 con los tatuajes que se hizo el int\u00e9rprete de \u2018Adi\u00f3s [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1322443,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[691],"tags":[754,749],"genre":[],"internal":[],"class_list":["post-1322438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-celebridades","tag-musica","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda - El Bot\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda - El Bot\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Tras un a\u00f1o y medio de relaci\u00f3n, Belinda y Christian Nodal anunciaron hace una semana, que hab\u00edan puesto punto final a su noviazgo y que seguir\u00edan por caminos separados. En medio de los rumores sobre las razones de su rompimiento, muchos han preguntado qu\u00e9 pasar\u00e1 con los tatuajes que se hizo el int\u00e9rprete de \u2018Adi\u00f3s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/\" \/>\n<meta property=\"og:site_name\" content=\"El Bot\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elbotonradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-21T20:04:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-21T20:15:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:site\" content=\"@elbotonradio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda\",\"datePublished\":\"2022-02-21T20:04:26+00:00\",\"dateModified\":\"2022-02-21T20:15:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/\"},\"wordCount\":321,\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg\",\"keywords\":[\"Celebridades\",\"M\u00fasica\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/\",\"url\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/\",\"name\":\"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda - El Bot\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg\",\"datePublished\":\"2022-02-21T20:04:26+00:00\",\"dateModified\":\"2022-02-21T20:15:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#primaryimage\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg\",\"width\":920,\"height\":613},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elboton.com\/los-angeles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#website\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"name\":\"El Bot\u00f3n\",\"description\":\"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.\",\"publisher\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#organization\",\"name\":\"Entravision\",\"url\":\"https:\/\/elboton.com\/los-angeles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"contentUrl\":\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png\",\"width\":255,\"height\":208,\"caption\":\"Entravision\"},\"image\":{\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/elbotonradio\/\",\"https:\/\/x.com\/elbotonradio\",\"https:\/\/www.tiktok.com\/@elbotonmusica?lang=es\",\"https:\/\/www.instagram.com\/elbotonradio\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/elboton.com\/ventura\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda - El Bot\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/","og_locale":"es_ES","og_type":"article","og_title":"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda - El Bot\u00f3n","og_description":"Tras un a\u00f1o y medio de relaci\u00f3n, Belinda y Christian Nodal anunciaron hace una semana, que hab\u00edan puesto punto final a su noviazgo y que seguir\u00edan por caminos separados. En medio de los rumores sobre las razones de su rompimiento, muchos han preguntado qu\u00e9 pasar\u00e1 con los tatuajes que se hizo el int\u00e9rprete de \u2018Adi\u00f3s [&hellip;]","og_url":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/","og_site_name":"El Bot\u00f3n","article_publisher":"https:\/\/www.facebook.com\/elbotonradio\/","article_published_time":"2022-02-21T20:04:26+00:00","article_modified_time":"2022-02-21T20:15:21+00:00","og_image":[{"width":920,"height":613,"url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg","type":"image\/jpeg"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_creator":"@elbotonradio","twitter_site":"@elbotonradio","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#article","isPartOf":{"@id":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda","datePublished":"2022-02-21T20:04:26+00:00","dateModified":"2022-02-21T20:15:21+00:00","mainEntityOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/"},"wordCount":321,"publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg","keywords":["Celebridades","M\u00fasica"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/","url":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/","name":"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda - El Bot\u00f3n","isPartOf":{"@id":"https:\/\/elboton.com\/los-angeles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#primaryimage"},"image":{"@id":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#primaryimage"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg","datePublished":"2022-02-21T20:04:26+00:00","dateModified":"2022-02-21T20:15:21+00:00","breadcrumb":{"@id":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#primaryimage","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg","width":920,"height":613},{"@type":"BreadcrumbList","@id":"https:\/\/elboton.com\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elboton.com\/los-angeles\/"},{"@type":"ListItem","position":2,"name":"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda"}]},{"@type":"WebSite","@id":"https:\/\/elboton.com\/los-angeles\/#website","url":"https:\/\/elboton.com\/los-angeles\/","name":"El Bot\u00f3n","description":"Toda la m\u00fasica latina y los mejores podcasts en espa\u00f1ol.","publisher":{"@id":"https:\/\/elboton.com\/los-angeles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elboton.com\/los-angeles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elboton.com\/los-angeles\/#organization","name":"Entravision","url":"https:\/\/elboton.com\/los-angeles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","contentUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/10\/evc-e.png","width":255,"height":208,"caption":"Entravision"},"image":{"@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elbotonradio\/","https:\/\/x.com\/elbotonradio","https:\/\/www.tiktok.com\/@elbotonmusica?lang=es","https:\/\/www.instagram.com\/elbotonradio\/"]},{"@type":"Person","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elboton.com\/los-angeles\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/elboton.com\/ventura\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/elboton.com\/ventura\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Christian Nodal ya se borr\u00f3 el primer tatuaje de Belinda","url":"http:\/\/elboton.com\/ventura\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/elboton.com\/ventura\/entretenimiento\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\/"},"thumbnailUrl":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg"},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"El Bot\u00f3n","logo":""},"keywords":["celebridades","m\u00fasica"],"dateCreated":"2022-02-21T20:04:26Z","datePublished":"2022-02-21T20:04:26Z","dateModified":"2022-02-21T20:15:21Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Christian Nodal ya se borr\\u00f3 el primer tatuaje de Belinda\",\"url\":\"http:\\\/\\\/elboton.com\\\/ventura\\\/entretenimiento\\\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elboton.com\\\/ventura\\\/entretenimiento\\\/christian-nodal-ya-se-borro-el-primer-tatuaje-de-belinda\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elboton.com\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"El Bot\\u00f3n\",\"logo\":\"\"},\"keywords\":[\"celebridades\",\"m\\u00fasica\"],\"dateCreated\":\"2022-02-21T20:04:26Z\",\"datePublished\":\"2022-02-21T20:04:26Z\",\"dateModified\":\"2022-02-21T20:15:21Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/elboton.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2022\/02\/WMFQRFUPGNHDLCSHHDS4OUCRII.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/posts\/1322438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/comments?post=1322438"}],"version-history":[{"count":5,"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/posts\/1322438\/revisions"}],"predecessor-version":[{"id":1322449,"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/posts\/1322438\/revisions\/1322449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/media\/1322443"}],"wp:attachment":[{"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/media?parent=1322438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/categories?post=1322438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/tags?post=1322438"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/genre?post=1322438"},{"taxonomy":"internal","embeddable":true,"href":"https:\/\/elboton.com\/ventura\/wp-json\/wp\/v2\/internal?post=1322438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}